{"id":856,"count":1,"description":"","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/","name":"Peuples autochtones","slug":"peuples-autochtones","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Peuples autochtones - Charleroi Pour la Palestine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/category\\\/peuples-autochtones\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/category\\\/peuples-autochtones\\\/\",\"name\":\"Archives des Peuples autochtones - Charleroi Pour la Palestine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/category\\\/peuples-autochtones\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/category\\\/peuples-autochtones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peuples autochtones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Peuples autochtones - Charleroi Pour la Palestine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/","name":"Archives des Peuples autochtones - Charleroi Pour la Palestine","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/category\/peuples-autochtones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Peuples autochtones"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts?categories=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}