{"id":11577,"date":"2015-12-05T11:31:00","date_gmt":"2015-12-05T10:31:00","guid":{"rendered":"https:\/\/charleroi-pourlapalestine.be\/?p=11577"},"modified":"2020-05-02T11:43:37","modified_gmt":"2020-05-02T09:43:37","slug":"apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme","status":"publish","type":"post","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/","title":{"rendered":"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme"},"content":{"rendered":"<div class=\"entry-content mh-clearfix\">\n<figure class=\"entry-thumbnail\"><\/figure>\n<div class=\"pf-content\">\n<p>C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme.<\/p>\n<p><a class=\"fancybox image\" href=\"https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4994 size-large\" src=\"https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683.jpg\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683.jpg 1024w, https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-400x267.jpg 400w, https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris.jpg 1200w\" alt=\"C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme\" width=\"1024\" height=\"683\"><\/a><\/p>\n<p>Quand je suis arriv\u00e9e \u00e0<strong> Paris<\/strong> dans la soir\u00e9e du vendredi 13 novembre, la personne qui m\u2019accueillait a demand\u00e9 \u00e0 notre chauffeur de taxi de nous emmener chez elle, rue de la Fontaine-au-Roi&nbsp;; le GPS du taxi affichait qu\u2019une fusillade y avait lieu au m\u00eame moment.<\/p>\n<p>Ce n\u2019est que le lendemain matin que nous avons compris tous les d\u00e9tails de la trag\u00e9die. Peu apr\u00e8s ce voyage \u00e0 <strong>Paris,<\/strong> je me suis rendue \u00e0 <strong>Bruxelles<\/strong>, pour y constater que l\u2019alerte s\u00e9curit\u00e9 y avait atteint le<em> \u00ab&nbsp;niveau quatre&nbsp;\u00bb<\/em> et que le m\u00e9tro et les \u00e9coles avaient \u00e9t\u00e9 ferm\u00e9s dans la crainte d\u2019un attentat terroriste.<\/p>\n<p>Le but de ces deux voyages \u00e9tait de r\u00e9pondre positivement \u00e0 des organisations de solidarit\u00e9 avec le peuple palestinien qui m\u2019avaient invit\u00e9e \u00e0 venir dialoguer avec le public en <strong>Europe<\/strong> sur la vie en <strong>Palestine occup\u00e9e.<\/strong><\/p>\n<p>J\u2019\u00e9prouve un attachement pour la <strong>France<\/strong>, o\u00f9 autrefois j\u2019ai habit\u00e9 et \u00e9tudi\u00e9, et o\u00f9 j\u2019ai gard\u00e9 des amis et des camarades.<\/p>\n<p>Je suis tourment\u00e9e par le massacre de ces innocents \u00e0 <strong>Paris<\/strong>, tout comme je le suis par le massacre du <strong>Liban<\/strong> \u00e0 <strong>Beyrouth<\/strong> le jour d\u2019avant, les massacres \u00e0 <strong>Bamako<\/strong> la semaine qui a suivi, et le r\u00e9cent massacre des manifestants pro-kurdes \u00e0 <strong>Ankara<\/strong> et des touristes russes dans le<strong> Sina\u00ef.<\/strong><\/p>\n<p>L\u2019angoisse pour moi est double&nbsp;: elle touche \u00e0 la perte de la vie de l\u2019&nbsp;<em>\u00ab&nbsp;autre&nbsp;\u00bb<\/em>, aussi bien qu\u2019\u00e0 l\u2019atteinte grave au syst\u00e8me de valeur de mon propre <em>\u00ab&nbsp;moi&nbsp;\u00bb<\/em> \u00e9tendu.<\/p>\n<p>Les attentats de <strong>Paris<\/strong> ont fourni une opportunit\u00e9 aux dirigeants isra\u00e9liens et \u00e0 leurs partisans, comme d\u2019habitude, pour discr\u00e9diter la r\u00e9sistance palestinienne \u00e0 l\u2019occupation militaire brutale d<strong>\u2019Isra\u00ebl.<\/strong><\/p>\n<p>Le Premier ministre a pr\u00e9tendu que ceux qui condamnaient les attentats de<strong> Paris<\/strong> sans condamner la violence contre les Isra\u00e9liens \u00e9taient des <em>\u00ab&nbsp;hypocrites et des aveugles. Derri\u00e8re ces attentats terroristes se tient l\u2019Islam radical, qui cherche \u00e0 nous d\u00e9truire, le m\u00eame Islam radical qui a frapp\u00e9 \u00e0<strong> Paris<\/strong> et menace l\u2019Europe tout enti\u00e8re&nbsp;\u00bb<\/em>.<\/p>\n<p>Poussant \u00e0 plus de pens\u00e9e binaire, \u00e0 une partition du<em> \u00ab&nbsp;nous contre eux&nbsp;\u00bb<\/em> et des <em>\u00ab&nbsp;bons contre les m\u00e9chants&nbsp;\u00bb<\/em>, il a ajout\u00e9, <em>\u00ab&nbsp;Comme je le dis depuis de nombreuses ann\u00e9es, le terrorisme islamique militant agresse nos soci\u00e9t\u00e9s parce qu\u2019il veut d\u00e9truire notre civilisation et nos valeurs&nbsp;\u00bb<\/em>.<\/p>\n<p>Le ministre de la D\u00e9fense d\u2019<strong>Isra\u00ebl, Moshe Ya\u2019alon<\/strong>, a d\u00e9clar\u00e9 dans une m\u00eame veine&nbsp;: <em>\u00ab&nbsp;Ce que nous avons, c\u2019est l\u2019Islam djihadiste qui appelle \u00e0 la destruction de la culture occidentale&nbsp;\u00bb.<\/em><\/p>\n<p>Ce clich\u00e9 est diffus\u00e9 alors m\u00eame que la plupart des victimes des groupes terroristes <em>\u00ab&nbsp;islamiques&nbsp;\u00bb<\/em> sont des musulmans, et que ces victimes sont souvent, tels les r\u00e9fugi\u00e9s palestiniens de <strong>Syrie<\/strong>, des adversaires d<strong>\u2019Isra\u00ebl.<\/strong><\/p>\n<p><em>\u00ab&nbsp;Ils veulent nous tuer parce que nous sommes juifs&nbsp;\u00bb<\/em>, ainsi s\u2019expriment les dirigeants isra\u00e9liens face aux actes de la r\u00e9sistance palestinienne, dans un d\u00e9ni total du contexte de l\u2019occupation. En <strong>France,<\/strong> un article de <strong>V\u00e9ronique Mortaigne<\/strong> et <strong>Nathalie Guilbert<\/strong>, publi\u00e9 dans <em>Le Monde<\/em> deux jours apr\u00e8s les attentats de <strong>Paris<\/strong>, a fait le lien entre l\u2019attentat contre le <strong>Bataclan<\/strong> et les appels ant\u00e9rieurs par des groupes pro-palestiniens au boycott de ce th\u00e9\u00e2tre parce qu\u2019il avait organis\u00e9 un gala au profit des soldats isra\u00e9liens.<\/p>\n<p>Malgr\u00e9 une condamnation prompte des attentats de <strong>Paris<\/strong> par les groupes de r\u00e9sistance islamiques palestiniens, et malgr\u00e9 l\u2019expression de leur solidarit\u00e9 avec leurs victimes, il a circul\u00e9, sur les m\u00e9dias sociaux en<strong> France<\/strong>, une photo datant de 2012 et montrant des <strong>Palestiniens<\/strong> c\u00e9l\u00e9brant la signature d\u2019un accord de r\u00e9conciliation, avec l\u2019affirmation mensong\u00e8re qu\u2019ils \u00e9taient en train de c\u00e9l\u00e9brer les attentats dans la capitale fran\u00e7aise.<\/p>\n<p>Ce n\u2019est que plus tard que cette imposture a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e.<\/p>\n<p>Il y a eu des allusions subtiles de journalistes isra\u00e9liens que l<strong>\u2019Europe<\/strong> m\u00e9ritait les attentats terroristes pour avoir adopt\u00e9 une politique d\u2019\u00e9tiquetage des produits pr\u00e9cis\u00e9ment s\u2019ils proviennent des colonies ill\u00e9gales isra\u00e9liennes, et aussi des d\u00e9clarations plus vigoureuses, comme celle du rabbin Dov Lior, <em>\u00ab&nbsp;Les m\u00e9chants de l\u2019Europe imbib\u00e9e de sang le m\u00e9ritent pour ce qu\u2019ils ont fait \u00e0 notre peuple il y a 70 ans&nbsp;\u00bb<\/em>.<\/p>\n<p>De telles opinions scandaleuses ont \u00e9t\u00e9 moins fr\u00e9quentes en<strong> Europe.<\/strong><\/p>\n<p>La v\u00e9rit\u00e9, c\u2019est que l\u2019<em>&nbsp;\u00ab&nbsp;\u00c9tat juif&nbsp;\u00bb<\/em> a \u00e9t\u00e9 cr\u00e9\u00e9 gr\u00e2ce \u00e0 une violence excessive et une agression contre les <strong>Palestiniens<\/strong>, peuple originaire de cette terre.<\/p>\n<p>Comme d\u2019autres peuples autochtones dont la terre a \u00e9t\u00e9 colonis\u00e9e, dont les ressources ont \u00e9t\u00e9 vol\u00e9es, et dont les familles et relations ont \u00e9t\u00e9 tu\u00e9es, les <strong>Palestiniens<\/strong> ont pu \u00eatre capables d\u2019utiliser la violence en repr\u00e9sailles contre leurs oppresseurs, et pour les dissuader de plus d\u2019oppression, tout en utilisant des campagnes non violentes et des canaux diplomatiques pour obtenir leur lib\u00e9ration.<\/p>\n<p>Tout cela \u00e9tant inclus totalement dans leurs droits issus de la l\u00e9gislation internationale.<\/p>\n<p>Les <strong>Palestiniens<\/strong> sont connus pour leur hospitalit\u00e9 envers les \u00e9trangers qui viennent en<strong> Palestine,<\/strong> pas pour les tuer.<\/p>\n<p>Dans des cas aussi rares que celui du meurtre du militant italien pro-Palestine Vittorio Arrigoni, par un groupe salafiste de<strong> Gaza<\/strong>, les auteurs ont \u00e9t\u00e9 punis par la loi, et condamn\u00e9s par tout l\u2019\u00e9ventail des partis politiques.<\/p>\n<p>\u00c0 l\u2019inverse, les meurtres d\u2019une liste interminable de militants et journalistes \u00e9trangers par l\u2019arm\u00e9e isra\u00e9lienne ont re\u00e7u leur justification (autod\u00e9fense), sans punition ni justice.<\/p>\n<p>Il est vrai que durant les ann\u00e9es 1970, certains <strong>Palestiniens<\/strong> ont pris des <strong>Isra\u00e9liens<\/strong> en otage, en des lieux ext\u00e9rieurs aux fronti\u00e8res de la <strong>Palestine historique<\/strong>, pour les \u00e9changer avec des prisonniers politiques \u2013 le plus spectaculaire \u00e9tant \u00e0<strong> Munich<\/strong> \u2013 mais dont les responsables \u00e9taient des groupes de r\u00e9sistance la\u00efcs, qui n\u2019ont jamais utilis\u00e9 la rh\u00e9torique islamique pour faire avancer leur id\u00e9ologie.<\/p>\n<p>Les groupes palestiniens islamiques ont toujours limit\u00e9 leur lutte \u00e0 la <strong>Palestine occup\u00e9e<\/strong>, et pas au-del\u00e0.<\/p>\n<p>Ce sont les<strong> Isra\u00e9liens<\/strong> qui se targuent que le<strong> Mossad<\/strong> (Institut pour les renseignements et les affaires sp\u00e9ciales) a tu\u00e9 des militants, des intellectuels palestiniens, des repr\u00e9sentants de l\u2019<strong>Organisation de lib\u00e9ration de la Palestine (OLP)<\/strong>, et d\u2019autres groupes de r\u00e9sistance, en <strong>Europe<\/strong> comme dans des capitales arabes.<\/p>\n<p>Il est ainsi plus justifi\u00e9 de comparer les tactiques de <strong>Daesh<\/strong> \u00e0 celles des groupes terroristes qui sont derri\u00e8re la fondation de l\u2019\u00c9tat d\u2019<strong>Isra\u00ebl<\/strong>, plut\u00f4t qu\u2019\u00e0 celles de la r\u00e9sistance palestinienne.<\/p>\n<p>Tant<strong> Daesh<\/strong> que l\u2019&nbsp;\u00ab<em>&nbsp;\u00c9tat juif&nbsp;\u00bb<\/em> se sont cr\u00e9\u00e9s gr\u00e2ce \u00e0 d\u2019\u00e9pouvantables massacres, entra\u00eenant une population de r\u00e9fugi\u00e9s dans leur sillage. Les deux font preuve d\u2019ambitions expansionnistes.<\/p>\n<p>La strat\u00e9gie de <strong>Daesh<\/strong> est d\u2019attaquer l\u2019Occident, avec l\u2019objectif de provoquer plus de discrimination \u00e0 l\u2019encontre des musulmans d\u2019Occident pour les sortir de la <em>\u00ab&nbsp;zone grise&nbsp;\u00bb<\/em>&nbsp;; le <strong>Mossad<\/strong> d\u2019<strong>Isra\u00ebl<\/strong> a \u00e9t\u00e9 \u00e0 l\u2019origine d\u2019attentats terroristes contre des juifs en <strong>Iraq<\/strong>, en<strong> \u00c9gypte<\/strong> et au <strong>Maroc<\/strong>, avec l\u2019objectif de les faire venir en<strong> Isra\u00ebl.<\/strong><\/p>\n<p>L\u2019op\u00e9ration <strong>Sushana<\/strong> dans laquelle des espions isra\u00e9liens ont programm\u00e9 des attentats \u00e0 la bombe contre des juifs \u00e9gyptiens&nbsp;; l\u2019attentat intentionnel et soutenu par des avions et des vedettes lance-torpilles isra\u00e9liens contre le <strong>USS Liberty<\/strong>, tuant 34 membres de l\u2019\u00e9quipage et en blessant 171 autres&nbsp;; et diff\u00e9rentes op\u00e9rations sous faux pavillon \u00e0 travers le monde, sont des exemples des crimes odieux perp\u00e9tr\u00e9s par les <strong>Isra\u00e9liens<\/strong> pour lesquels les responsabilit\u00e9s ont \u00e9t\u00e9 imput\u00e9es ailleurs.<\/p>\n<p>En plus de tirer un profit politique en reformulant l\u2019occupation de la<strong> Palestine<\/strong>, en imposant une politique isra\u00e9lienne comme une <em>\u00ab&nbsp;guerre contre le terrorisme&nbsp;\u00bb<\/em> et en diffamant le caract\u00e8re des<strong> Palestiniens,<\/strong> les pr\u00e9sentant comme des terroristes inhumains, barbares, <strong>Isra\u00ebl<\/strong> se saisit aussi de l\u2019opportunit\u00e9 actuelle pour colporter son appareil et sa politique de s\u00e9curit\u00e9 comme un<em> \u00ab&nbsp;savoir-faire&nbsp;\u00bb<\/em> test\u00e9 sur le terrain contre les<strong> Palestiniens<\/strong>.<\/p>\n<p>Ce <em>\u00ab&nbsp;savoir-faire&nbsp;\u00bb<\/em> a \u00e9t\u00e9 utilis\u00e9 pour r\u00e9primer la libert\u00e9 et la d\u00e9mocratie en<strong> Europe<\/strong> et pour exacerber une <em>\u00ab&nbsp;guerre contre le terrorisme&nbsp;\u00bb<\/em> dont les victimes comprennent d\u00e9j\u00e0 plus de 4000 civils. \u00c0 un moment o\u00f9 <strong>Isra\u00ebl<\/strong> rabaisse l\u2019\u00e2ge de la responsabilit\u00e9 p\u00e9nale pour les enfants palestiniens \u00e0 12 ans, les envoyant dans les centres d\u2019interrogatoire et les soumettant \u00e0 la torture, nous ne pouvons qu\u2019esp\u00e9rer que l\u2019<strong>Europe<\/strong> s\u2019avancera vers une expansion de son syst\u00e8me l\u00e9gislatif d\u00e9mocratique et ses efforts pour les droits de l\u2019homme, avec l\u2019objectif d\u2019aider les<strong> Palestiniens<\/strong> dans leur qu\u00eate de justice sur leurs territoires actuellement occup\u00e9s.<\/p>\n<p>C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme, et non par la r\u00e9pression, la pens\u00e9e binaire et l\u2019exportation des <em>\u00ab&nbsp;le\u00e7ons&nbsp;\u00bb<\/em> isra\u00e9liennes vers l\u2019<strong>Europe.<\/strong><\/p>\n<hr>\n<p>Publi\u00e9 le 2 d\u00e9cembre sur <a href=\"https:\/\/www.middleeastmonitor.com\/articles\/europe\/22610-in-the-aftermath-of-paris-the-israeli-way-is-not-the-answer\" target=\"_blank\" rel=\"noopener noreferrer\">Middle East Monitor<\/a><\/p>\n<p>Traduction&nbsp;: JPP pour <a href=\"http:\/\/amisdejayyous.monsite-orange.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">les Amis de Jayyous<\/a><\/p>\n<figure id=\"attachment_5015\" class=\"wp-caption alignleft\" aria-describedby=\"caption-attachment-5015\"><a class=\"fancybox image\" href=\"https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Samah-Jabr.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5015 size-thumbnail\" src=\"https:\/\/www.pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Samah-Jabr-150x150.png\" alt=\"\" width=\"150\" height=\"150\"><\/a><figcaption id=\"caption-attachment-5015\" class=\"wp-caption-text\">Samah Jabr<\/figcaption><\/figure>\n<p><strong>Samah Jabr <\/strong>est est une Palestinienne de J\u00e9rusalem, psychiatre et psychoth\u00e9rapeute, d\u00e9vou\u00e9e au bien-\u00eatre de sa communaut\u00e9, au-del\u00e0 des questions de la maladie mentale<\/p>\n<p><a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/tag\/samah-jabr\/\">D\u2019autres articles de Samah Jabr ou parlant d\u2019elle, sur ce site.<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme<\/p>\n","protected":false},"author":1,"featured_media":11582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[136,95,107],"tags":[396],"class_list":["post-11577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-france","category-hasbara-propagande-israelienne","category-services-secrets-israeliens","tag-samah-jabr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme<\/title>\n<meta name=\"description\" content=\"C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/\"},\"author\":{\"name\":\"admin1873\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\"},\"headline\":\"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme\",\"datePublished\":\"2015-12-05T10:31:00+00:00\",\"dateModified\":\"2020-05-02T09:43:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/\"},\"wordCount\":1687,\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Paris-1024x683-1-e1588412568516.jpg\",\"keywords\":[\"Samah Jabr\"],\"articleSection\":[\"France\",\"Hasbara\",\"Services secrets\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/\",\"name\":\"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Paris-1024x683-1-e1588412568516.jpg\",\"datePublished\":\"2015-12-05T10:31:00+00:00\",\"dateModified\":\"2020-05-02T09:43:37+00:00\",\"description\":\"C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Paris-1024x683-1-e1588412568516.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/Paris-1024x683-1-e1588412568516.jpg\",\"width\":520,\"height\":347},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2015\\\/12\\\/05\\\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\",\"name\":\"admin1873\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/author\\\/admin1873\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme","description":"C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#article","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/"},"author":{"name":"admin1873","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa"},"headline":"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme","datePublished":"2015-12-05T10:31:00+00:00","dateModified":"2020-05-02T09:43:37+00:00","mainEntityOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/"},"wordCount":1687,"publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683-1-e1588412568516.jpg","keywords":["Samah Jabr"],"articleSection":["France","Hasbara","Services secrets"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/","name":"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#primaryimage"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683-1-e1588412568516.jpg","datePublished":"2015-12-05T10:31:00+00:00","dateModified":"2020-05-02T09:43:37+00:00","description":"C\u2019est avec plus de d\u00e9mocratie, plus de solidarit\u00e9 et plus de politique en faveur des droits humains, et plus d\u2019anti-imp\u00e9rialisme, qu\u2019il sera mis fin au terrorisme","breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#primaryimage","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683-1-e1588412568516.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2015\/12\/Paris-1024x683-1-e1588412568516.jpg","width":520,"height":347},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2015\/12\/05\/apres-paris-la-maniere-israelienne-nest-pas-la-reponse-au-terrorisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Apr\u00e8s Paris, la mani\u00e8re isra\u00e9lienne n\u2019est pas la r\u00e9ponse au terrorisme"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]},{"@type":"Person","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa","name":"admin1873","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/author\/admin1873\/"}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/11577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/comments?post=11577"}],"version-history":[{"count":0,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/11577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media\/11582"}],"wp:attachment":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media?parent=11577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories?post=11577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/tags?post=11577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}