{"id":24324,"date":"2021-03-24T04:14:25","date_gmt":"2021-03-24T03:14:25","guid":{"rendered":"https:\/\/charleroi-pourlapalestine.be\/?p=24324"},"modified":"2021-03-24T04:18:04","modified_gmt":"2021-03-24T03:18:04","slug":"ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne","status":"publish","type":"post","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/","title":{"rendered":"Une Palestinienne de plus meurt au cours d\u2019un raid nocturne de l\u2019arm\u00e9e isra\u00e9lienne"},"content":{"rendered":"<p>Une Palestinienne de 69 ans est tomb\u00e9e morte d\u2019une crise cardiaque chez elle, quand des soldats isra\u00e9liens ont fait irruption au milieu de la nuit pour arr\u00eater un parent qui n\u2019\u00e9tait d\u2019ailleurs pas pr\u00e9sent. L\u2019an dernier, les troupes isra\u00e9liennes ont forc\u00e9 l\u2019entr\u00e9e de quelque 2&nbsp;500 maisons en Cisjordanie.<\/p>\n<div id=\"attachment_24334\" style=\"width: 464px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24334\" class=\"wp-image-24334 size-full\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png\" alt=\"\" width=\"454\" height=\"320\"><p id=\"caption-attachment-24334\" class=\"wp-caption-text\">Ali Dalu et une de ses filles &#8211; Photo : Alex Levac<\/p><\/div>\n<p><a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/tag\/gideon-levy\/\">Gideon Levy<\/a> \/ Alex Levac, 11 mars 2021<\/p>\n<p>La soir\u00e9e \u00e9tait agr\u00e9able, au domicile de la famille <strong>Dalu,<\/strong> dans le petit village d\u2019<strong>Abu Nujaym<\/strong>, perch\u00e9 en bordure du d\u00e9sert de <strong>Jud\u00e9e, <\/strong>pr\u00e8s de<strong> Bethl\u00e9em, <\/strong>en <strong>Cisjordanie<\/strong>. Une grand-m\u00e8re, <strong>Rahma Dalu<\/strong>, regardait la t\u00e9l\u00e9vision avec son fils, sa belle-fille et ses petits-enfants, ainsi qu\u2019un voisin, avant d\u2019aller au lit, un peu avant minuit. \u00c0 1&nbsp;h&nbsp;15, les habitants de la maison ont \u00e9t\u00e9 brusquement \u00e9veill\u00e9s par des bruits. Les enfants sont rest\u00e9s endormis mais <strong>Ali Dalu<\/strong>, le fils de <strong>Rahma<\/strong>, s\u2019est redress\u00e9 dans son lit, pris de peur. Sa m\u00e8re, qui dormait dans la chambre voisine, s\u2019\u00e9tait \u00e9veill\u00e9e elle aussi \u00e0 cause des all\u00e9es et venues de l\u2019autre c\u00f4t\u00e9 de sa fen\u00eatre. Elle aussi devait avoir \u00e9t\u00e9 tr\u00e8s effray\u00e9e.<\/p>\n<p>Une <strong>vingtaine<\/strong> de soldats des <em>Forces de d\u00e9fense isra\u00e9liennes (FDI)<\/em> se trouvaient <strong>dans la cour de la maison, accompagn\u00e9s d\u2019un chien ou deux.<\/strong> Les hommes <strong>grimp\u00e8rent jusqu\u2019au deuxi\u00e8me \u00e9tage de l\u2019immeuble<\/strong>, qui en compte quatre, \u00e0 la recherche du cousin d\u2019<strong>Ali<\/strong>, <strong>Mohammed Abu Aahur<\/strong>, un homme divorc\u00e9 de 30 ans qui travaille dans le studio de son p\u00e8re, \u00e0 Bethl\u00e9em.<\/p>\n<p><strong>Ali<\/strong>, 45 ans, toujours assis dans son lit, entendit une toux de plus en plus bruyante venant de la chambre de sa m\u00e8re, en face de la cour o\u00f9 les soldats allaient et venaient. Il se pr\u00e9cipita dans la chambre&nbsp;; elle est pleine de couleurs, avec des cages \u00e0 oiseaux accroch\u00e9es aux murs et un lit de fer orn\u00e9 d\u2019une couverture pourpre. <strong>Rahma<\/strong> \u00e9tait assise dans son lit. Elle se plaignait d\u2019avoir mal \u00e0 la poitrine et elle respirait difficilement. <strong>Ali<\/strong> ne savait pas que c\u2019\u00e9taient les derni\u00e8res bouff\u00e9es d\u2019air que sa m\u00e8re de 69 ans allait prendre.<\/p>\n<p>Le 17 f\u00e9vrier 2021, les FDI avaient d\u00e9j\u00e0 fait irruption dans la maison des<strong> Dalu. Rahma<\/strong> n\u2019avait pas dit qu\u2019elle se sentait mal, ce soir-l\u00e0, nous explique aujourd\u2019hui son fils&nbsp;; elle s\u2019\u00e9tait administr\u00e9 elle-m\u00eame son injection nocturne d\u2019insuline pour son diab\u00e8te et \u00e9tait all\u00e9e se coucher. Trois mois plus t\u00f4t, elle avait eu une l\u00e9g\u00e8re attaque \u2013 mais elle \u00e9tait ressortie de l\u2019<strong>h\u00f4pital Al-Hussein<\/strong>, dans la ville voisine de <strong>Beit Jala<\/strong>, sans dommage notable et elle s\u2019\u00e9tait sentie bien depuis lors.<\/p>\n<p>Le cousin, <strong>Mohammed Abu Aahur<\/strong>, un photographe sp\u00e9cialis\u00e9 dans les mariages, vit \u00e0 l\u2019\u00e9tage. L\u2019an dernier, des soldats l\u2019ont arr\u00eat\u00e9. Selon<strong> Ali,<\/strong> ils avaient trait\u00e9 les autres membres de la famille avec respect. <strong>Abu Aahur<\/strong> \u00e9tait accus\u00e9 d\u2019\u00eatre en possession de <strong>p\u00e9tards<\/strong> et autres pi\u00e8ces pour feu d\u2019artifice, et de tirer en l\u2019air&nbsp;lors de mariages. Il avait \u00e9t\u00e9 condamn\u00e9 \u00e0 quatre mois de prison pour avoir \u00e9t\u00e9 en possession d\u2019armes et s\u2019\u00e9tait en outre vu infliger une amende de 25&nbsp;000 shekels (soit environ 7&nbsp;775 USD). Il n\u2019avait jamais \u00e9t\u00e9 arr\u00eat\u00e9 auparavant et, d\u2019apr\u00e8s sa famille, il n\u2019est actif dans aucune organisation politique. &nbsp;<\/p>\n<p>Ensuite, le 17 f\u00e9vrier, des soldats \u00e9taient venus l\u2019arr\u00eater \u00e0 nouveau. Ils avaient \u00e9veill\u00e9 son p\u00e8re, <strong>Ibrahim Abu Aahur,<\/strong> qui vit \u00e0 l\u2019\u00e9tage au-dessus, et lui avaient ordonn\u00e9 d\u2019ouvrir la porte de l\u2019appartement de son fils. <strong>Mohammed<\/strong> n\u2019\u00e9tait pas l\u00e0 \u2013 il dormait chez un ami. Les soldats avaient effectu\u00e9 une perquisition compl\u00e8te, laissant les matelas et un tas d\u2019autres affaires p\u00eale-m\u00eale sur le sol. <strong>Ali<\/strong> raconte que le p\u00e8re de <strong>Mohammed<\/strong> avait dit aux soldats qu\u2019il pouvait appeler son fils et lui demander de revenir chez lui, mais les soldats lui avaient dit que ce n\u2019\u00e9tait pas n\u00e9cessaire. Il y avait toujours des affiches sur les murs pour f\u00e9liciter <strong>Abu Aahur<\/strong> d\u2019\u00eatre sorti de prison quelques semaines plus t\u00f4t&nbsp;; les soldats les avaient arrach\u00e9es des murs et les avaient d\u00e9chir\u00e9es. Pendant que tout cela se passait \u2013 cela avait dur\u00e9 une heure environ, se souvient<strong> Ali<\/strong> \u2013, il avait eu peur de quitter son appartement et l\u2019\u00e9tat de sa m\u00e8re n\u2019avait cess\u00e9 de se d\u00e9t\u00e9riorer.<\/p>\n<div id=\"attachment_24333\" style=\"width: 189px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-24333\" class=\"wp-image-24333 size-medium\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-femme-179x300.png\" alt=\"\" width=\"179\" height=\"300\" srcset=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-femme-179x300.png 179w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-femme.png 347w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/><p id=\"caption-attachment-24333\" class=\"wp-caption-text\">Rahma Dula &#8211; Photo de la famille<\/p><\/div>\n<p><strong>Ali<\/strong> \u00e9veilla sa femme, <strong>Rana<\/strong>, 32 ans, qui avait continu\u00e9 de dormir malgr\u00e9 tout ce tapage, et lui dit qu\u2019il devait emmener sa m\u00e8re \u00e0 l\u2019h\u00f4pital. <strong>Rahma<\/strong> avait essay\u00e9 de s\u2019habiller toute seule, mais elle \u00e9tait incapable de se mettre debout. <strong>Ali <\/strong>et<strong> Rana<\/strong> craignaient de demander de l\u2019aide \u00e0 d\u2019autres proches dans l\u2019immeuble, du fait que les soldats \u00e9taient toujours l\u00e0 mais, d\u2019une fa\u00e7on ou d\u2019une autre, il parvint quand m\u00eame \u00e0 emmener <strong>Rahma<\/strong> jusqu\u2019\u00e0 leur voiture. Les soldats ne les emp\u00each\u00e8rent pas de sortir de la maison ni de s\u2019en aller, pas plus qu\u2019ils ne propos\u00e8rent leur aide. <strong>Rahma<\/strong> gisait sur le si\u00e8ge arri\u00e8re, la t\u00eate pos\u00e9e sur le giron de <strong>Rana<\/strong>, pendant qu\u2019<strong>Ali<\/strong> \u00e9tait en route vers l\u2019<strong>h\u00f4pital Al-Hussein<\/strong>, \u00e0 une dizaine de kilom\u00e8tres de l\u00e0. Mais, juste avant d\u2019arriver, alors qu\u2019il ne restait plus que 200 m\u00e8tres environ \u00e0 parcourir, <strong>Rahma<\/strong> cessa de respirer. Les efforts de la faire revenir \u00e0 la vie furent inutiles. Les m\u00e9decins confirm\u00e8rent son d\u00e9c\u00e8s. Cause de la mort&nbsp;: infarctus du myocarde. <strong>Rahma<\/strong> fut enterr\u00e9e le seul jour du mois dernier o\u00f9 il neigea&nbsp;; on l\u2019ensevelit dans la parcelle familiale pr\u00e8s du tombeau de Rachel [les musulmans appellent ce site \u00ab&nbsp;mosqu\u00e9e Bilal bin Rabah, NdT], \u00e0 <strong>Bethl\u00e9em<\/strong>.<\/p>\n<p>L\u2019Unit\u00e9 du porte-parole des FDI a adress\u00e9 la r\u00e9ponse suivante aux questions de <em>Haaretz<\/em> sur la raison du raid dans la maison d\u2019Abu Nujaym&nbsp;: <em>\u00ab&nbsp;Au cours de la nuit du 17 f\u00e9vrier 2021, les FDI ont effectu\u00e9 une recherche d\u2019armes dans une maison du village d\u2019Abu Nujaym, qui est sous la juridiction de la brigade territoriale d\u2019Etzion. Suite \u00e0 un rapport remis apr\u00e8s l\u2019op\u00e9ration et concernant le d\u00e9c\u00e8s d\u2019un membre de la famille d\u2019un r\u00e9sident de l\u2019immeuble, les faits feront l\u2019objet d\u2019une enqu\u00eate.&nbsp;\u00bb<\/em><\/p>\n<p><strong>Ali<\/strong> nous dit ici qu\u2019il ne bl\u00e2me personne du d\u00e9c\u00e8s de sa m\u00e8re. Il nie carr\u00e9ment toute rumeur pr\u00e9tendant qu\u2019elle a \u00e9t\u00e9 battue par les soldats avant de mourir. Les militaires ne sont m\u00eame pas entr\u00e9s dans leur appartement, dit-il. Est-elle d\u00e9c\u00e9d\u00e9e de peur en entendant les militaires de l\u2019autre c\u00f4t\u00e9 de sa fen\u00eatre, en pleine nuit, et est-ce cela qui a provoqu\u00e9 son accident cardiaque&nbsp;? Rien ne permet de l\u2019affirmer. Mais une question d\u00e9range&nbsp;: <strong>Pourquoi les soldats ont-ils fait tout ce cirque pr\u00e9alable, comme ils le font dans tant de maisons palestiniennes, chaque nuit&nbsp;?<\/strong> De plus, <strong>Mohammed Abu Aahur<\/strong> a v\u00e9cu chez lui sans le moindre probl\u00e8me depuis l\u2019incident d\u2019il y a quelques semaines, et il&nbsp;ne se cache pas&nbsp;; pour autant que l\u2019on sache, il n\u2019est pas recherch\u00e9 par les autorit\u00e9s isra\u00e9liennes. L\u2019arm\u00e9e n\u2019est pas revenue chez lui depuis lors. <strong>Pourquoi, dans ce cas, a-t-elle organis\u00e9 ce raid&nbsp;?<\/strong><\/p>\n<p>Son cousin <strong>Ali<\/strong> est convaincu que <strong>les militaires \u00e9taient impliqu\u00e9s dans un exercice en vue de les entra\u00eener \u00e0 effectuer des arrestations.<\/strong> Ce ne serait pas la premi\u00e8re fois que des soldats proc\u00e8dent de la sorte \u2013 <strong>faire se lever des femmes, des hommes, des personnes \u00e2g\u00e9es et des enfants alors qu\u2019ils sont profond\u00e9ment endormis dans leurs lits<\/strong>. <strong>Ce n\u2019est pas non plus la premi\u00e8re fois que des gens meurent au cours d\u2019activit\u00e9s nocturnes aussi effrayantes.<\/strong><\/p>\n<p>L\u2019organisation isra\u00e9lienne des droits humains<strong> B\u2019Tselem<\/strong> a r\u00e9pertori\u00e9 un certain nombre d\u2019\u00e9pisodes similaires. Le 26 novembre 2008, <strong>Hikmat Shukari al-Sheikh<\/strong> est morte d\u2019une crise cardiaque quand des soldats sont venus arr\u00eater son fils au camp de r\u00e9fugi\u00e9s de <strong>Qalandiyah.<\/strong> Le 18 septembre 2018, <strong>Mohammed Khatib,<\/strong> de <strong>Beit Rima<\/strong>, est d\u00e9c\u00e9d\u00e9 quelques heures apr\u00e8s avoir \u00e9t\u00e9 arr\u00eat\u00e9 \u00e0 son domicile. <strong>Mussa Abu Miala,<\/strong> 67 ans, du camp de <strong>Shoafat<\/strong>, a \u00e9t\u00e9 bless\u00e9 la nuit du 1er juin 2019, quand il a \u00e9t\u00e9 bouscul\u00e9 par des <strong>hommes de la police des fronti\u00e8res d\u00e9guis\u00e9s en Arabes<\/strong>, et qui \u00e9taient venus arr\u00eater son petit-fils. Il \u00e9tait mort 18 jours plus tard des complications r\u00e9sultant de sa blessure.<\/p>\n<p>En un sens, plus p\u00e9nible encore que les d\u00e9c\u00e8s, c\u2019est <strong>le nombre de raids nocturnes et autres op\u00e9rations d\u2019arrestation dont certains n\u2019ont d\u2019autre but que de semer la peur, de faire une d\u00e9monstration de contr\u00f4le et de force, ou dans le cadre de l\u2019entra\u00eenement des troupes afin qu\u2019elles puissent entretenir leur vigilance<\/strong>. Naturellement, le fait que la plupart de ces op\u00e9rations sont en contradiction flagrante avec les accords d\u2019<strong>Oslo<\/strong> ne suscite plus le moindre int\u00e9r\u00eat en Isra\u00ebl.<\/p>\n<p>Selon les donn\u00e9es de <strong>B\u2019Tselem<\/strong>, en 2020, une ann\u00e9e relativement calme, les forces de s\u00e9curit\u00e9 isra\u00e9liennes ont effectu\u00e9 au moins<strong> 3&nbsp;000 raids nocturnes dans les villes et villages palestiniens<\/strong>. Ils ont fait irruption dans pas moins de<strong> 2&nbsp;480 maisons<\/strong> et ont r\u00e9veill\u00e9 brutalement leurs occupants. Selon les donn\u00e9es du quartier g\u00e9n\u00e9ral palestinien de coordination et de liaison, depuis le d\u00e9but 2021 jusque ce lundi dernier, les<strong> FDI<\/strong> et le service de s\u00e9curit\u00e9 du <strong>Shin Bet<\/strong> ont effectu\u00e9 <strong>692 patrouilles et 627 raids dans des maisons de villes et villages palestiniens, arr\u00eatant 731 Palestiniens, dont 63 mineurs d\u2019\u00e2ge<\/strong>. <strong>Aucune nuit, pour ainsi dire, ne se passe sans qu\u2019il y ait un raid ou une arrestation. Et, chaque fois, c\u2019est effrayant. On peut m\u00eame en mourir.<\/strong><\/p>\n<hr>\n<p>Publi\u00e9 sur <a href=\"https:\/\/www.haaretz.com\/israel-news\/twilight-zone\/.premium.MAGAZINE-it-s-not-the-first-time-a-palestinian-dies-this-way-during-a-nighttime-idf-raid-1.9613030\" target=\"_blank\" rel=\"noopener noreferrer\">Haaretz<\/a> le 11 mars 2021<br \/>\nTraduction : Jean-Marie Fl\u00e9mal, <a href=\"https:\/\/charleroi-pourlapalestine.be\/\">Charleroi pour la Palestine<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gideon Levy : Aucune nuit, pour ainsi dire, ne se passe sans qu\u2019il y ait un raid ou une arrestation. Et, chaque fois, c\u2019est effrayant. On peut m\u00eame en mourir.<\/p>\n","protected":false},"author":1,"featured_media":24334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7,47,362],"tags":[],"class_list":["post-24324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cisjordanie","category-loccupation-militaire","category-repression-lautorite-palestinienne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une Palestinienne de plus meurt au cours d\u2019un raid de l\u2019arm\u00e9e isra\u00e9lienne<\/title>\n<meta name=\"description\" content=\"Une Palestinienne de 69 ans est tomb\u00e9e morte d\u2019une crise cardiaque chez elle, quand des soldats isra\u00e9liens ont fait irruption au milieu de la nuit\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/\"},\"author\":{\"name\":\"admin1873\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\"},\"headline\":\"Une Palestinienne de plus meurt au cours d\u2019un raid nocturne de l\u2019arm\u00e9e isra\u00e9lienne\",\"datePublished\":\"2021-03-24T03:14:25+00:00\",\"dateModified\":\"2021-03-24T03:18:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/\"},\"wordCount\":1806,\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png\",\"articleSection\":[\"Cisjordanie\",\"Occupation\",\"R\u00e9pression\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/\",\"name\":\"Une Palestinienne de plus meurt au cours d\u2019un raid de l\u2019arm\u00e9e isra\u00e9lienne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png\",\"datePublished\":\"2021-03-24T03:14:25+00:00\",\"dateModified\":\"2021-03-24T03:18:04+00:00\",\"description\":\"Une Palestinienne de 69 ans est tomb\u00e9e morte d\u2019une crise cardiaque chez elle, quand des soldats isra\u00e9liens ont fait irruption au milieu de la nuit\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png\",\"width\":454,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2021\\\/03\\\/24\\\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une Palestinienne de plus meurt au cours d\u2019un raid nocturne de l\u2019arm\u00e9e isra\u00e9lienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\",\"name\":\"admin1873\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/author\\\/admin1873\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une Palestinienne de plus meurt au cours d\u2019un raid de l\u2019arm\u00e9e isra\u00e9lienne","description":"Une Palestinienne de 69 ans est tomb\u00e9e morte d\u2019une crise cardiaque chez elle, quand des soldats isra\u00e9liens ont fait irruption au milieu de la nuit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#article","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/"},"author":{"name":"admin1873","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa"},"headline":"Une Palestinienne de plus meurt au cours d\u2019un raid nocturne de l\u2019arm\u00e9e isra\u00e9lienne","datePublished":"2021-03-24T03:14:25+00:00","dateModified":"2021-03-24T03:18:04+00:00","mainEntityOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/"},"wordCount":1806,"publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png","articleSection":["Cisjordanie","Occupation","R\u00e9pression"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/","name":"Une Palestinienne de plus meurt au cours d\u2019un raid de l\u2019arm\u00e9e isra\u00e9lienne","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#primaryimage"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png","datePublished":"2021-03-24T03:14:25+00:00","dateModified":"2021-03-24T03:18:04+00:00","description":"Une Palestinienne de 69 ans est tomb\u00e9e morte d\u2019une crise cardiaque chez elle, quand des soldats isra\u00e9liens ont fait irruption au milieu de la nuit","breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#primaryimage","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2021\/03\/Capture-d\u2019\u00e9cran-famille-e1616555133920.png","width":454,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2021\/03\/24\/ce-nest-pas-la-premiere-fois-qu-un-e-palestinien-ne-meurt-ainsi-au-cours-dun-raid-nocturne-de-larmee-israelienne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Une Palestinienne de plus meurt au cours d\u2019un raid nocturne de l\u2019arm\u00e9e isra\u00e9lienne"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]},{"@type":"Person","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa","name":"admin1873","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/author\/admin1873\/"}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/24324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/comments?post=24324"}],"version-history":[{"count":0,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/24324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media\/24334"}],"wp:attachment":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media?parent=24324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories?post=24324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/tags?post=24324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}