{"id":44337,"date":"2022-09-24T13:35:34","date_gmt":"2022-09-24T11:35:34","guid":{"rendered":"https:\/\/charleroi-pourlapalestine.be\/?p=44337"},"modified":"2022-09-24T13:57:44","modified_gmt":"2022-09-24T11:57:44","slug":"ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance","status":"publish","type":"post","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/","title":{"rendered":"Ahed Tamimi : <em>\u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb<\/em>"},"content":{"rendered":"<p>Dans une interview publi\u00e9 sur le site du journal<a href=\"https:\/\/www.demorgen.be\/nieuws\/de-palestijnse-die-de-wereld-rondging-toen-ze-een-israelische-soldaat-sloeg-we-willen-jullie-tranen-niet~b978fb1c\/?referrer=https%3A%2F%2Fwww.google.com%2F\" target=\"_blank\" rel=\"noopener\"> De Morgen<\/a>, <a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/tag\/ahed-tamimi\/\"><strong>Ahed Tamimi<\/strong> <\/a>affirme :<em> \u00ab\u00a0Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.\u00a0\u00bb<\/em><\/p>\n<div id=\"attachment_44340\" style=\"width: 786px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-44340\" class=\"wp-image-44340 size-large\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/09\/IMG_20220924_094928-776x1024.jpg\" alt=\"\" width=\"776\" height=\"1024\"><p id=\"caption-attachment-44340\" class=\"wp-caption-text\"><strong>Photo : Plate-forme Charleroi-Palestine (*)<\/strong><\/p><\/div>\n<p><strong><br \/>Ans Boersma<\/strong>, 22 septembre 2022<\/p>\n<p>Une adolescente v\u00eatue d\u2019un t-shirt rose et qui gifle un soldat isra\u00e9lien arm\u00e9. La vid\u00e9o d\u2019Ahed Tamimi (21 ans) a fait le tour du monde, en 2017. \u00c0 16 ans, Ahed s\u2019est retrouv\u00e9e en prison. Aujourd\u2019hui, elle \u00e9tudie le droit. <em>\u00ab Ma g\u00e9n\u00e9ration ne croit plus dans la paix. \u00bb<\/em><\/p>\n<p><strong>Dans ton livre qui vient de sortir, <em>They Called Me a Lioness : A Palestinian Girl&rsquo;s Fight for Freedom<\/em> (Ils me traitaient de lionne : Une jeune Palestinienne se bat pour la libert\u00e9), tu parles du temps que tu as pass\u00e9 en prison. Adolescente, tu as subi de tr\u00e8s longs interrogatoires au cours desquels on voulait te faire parler, mais tu n\u2019as pas baiss\u00e9 la t\u00eate. Comment as-tu pu rester mentalement forte ? <\/strong><\/p>\n<p>\u00ab Pour dire les choses simplement, les <em>Palestiniens<\/em> sont ainsi faits. Si on craque en prison, c\u2019est une honte. Je pensais \u00e0 mon p\u00e8re, comment il a \u00e9t\u00e9 tortur\u00e9 en prison. Et je pensais \u00e0 tous les autres d\u00e9tenus <em>palestiniens<\/em> qui ont refus\u00e9 de parler. C\u2019est ainsi que je suis rest\u00e9e forte. \u00bb<\/p>\n<p><strong>Dans ton livre, tu \u00e9cris que tu t\u2019es sentie coupable, quand tu as \u00e9t\u00e9 lib\u00e9r\u00e9e, et que tu t\u2019es retrouv\u00e9e en d\u00e9pression. Comment \u00e7a va, maintenant ? <\/strong><\/p>\n<p>\u00ab Je ne me sentais pas coupable d\u2019\u00eatre sortie de prison. Je me sentais coupable et impuissante parce que je ne pouvais rien faire pour tous ceux qui s\u2019y trouvaient encore. Mais, au bout d\u2019un temps, j\u2019ai surmont\u00e9 ce sentiment et, aujourd\u2019hui, je m\u2019engage dans ce qui rapproche le plus les prisonniers de la libert\u00e9. Rien de ce qui est b\u00e2ti sur l\u2019injustice et le pouvoir n\u2019est \u00e9ternel, et cela me donne de l\u2019espoir. \u00bb<\/p>\n<p><strong>Tu as \u00e9t\u00e9 invit\u00e9e \u00e0 prendre la parole au festival de gauche, Manifiesta, \u00e0 Ostende. Quel y a \u00e9t\u00e9 ton principal message ? <\/strong><\/p>\n<p>\u00ab Que les gens ne doivent pas nous percevoir comme des victimes. Nous ne voulons pas de vos larmes. On nous asperge quotidiennement de gaz lacrymog\u00e8ne et, des larmes, nous en avons assez. Je ne dis pas : Comme c\u2019est fantastique que vous souteniez la cause <em>palestinienne<\/em> ! Non. Je dis : Nous payons le prix des erreurs que vos gouvernements ont commises dans le pass\u00e9.<\/p>\n<p>\u00ab Il est du devoir des gens en Europe de soutenir la <em>Palestine<\/em> et de participer \u00e0 la lutte. Montrez votre solidarit\u00e9 en boycottant <em>Isra\u00ebl <\/em>politiquement, \u00e9conomiquement et culturellement. Cela me frustre que je ne doive pas seulement me battre pour la <em>Palestine, <\/em>mais que je doive \u00e9galement expliquer la vie sous l\u2019occupation \u00e0 la communaut\u00e9 internationale. J\u2019ai d\u2019autres r\u00eaves aussi. Je voulais devenir footballeuse, mais j\u2019ai renonc\u00e9 \u00e0 ce r\u00eave de fa\u00e7on \u00e0 pouvoir lutter pour la <em>Palestine<\/em>. \u00bb<\/p>\n<p><strong>Les gens voient en toi une dirigeante en devenir, mais tu n\u2019as pas d\u2019ambition politique. Pourquoi as-tu choisi des \u00e9tudes de droit ? <\/strong><\/p>\n<p>\u00ab J\u2019\u00e9tudie le droit afin de pouvoir lutter pour la justice qui nous est refus\u00e9e. Et pour modifier les lois, car je ne crois pas dans le syst\u00e8me juridique actuel. \u00bb<\/p>\n<p><strong>Quelle est la diff\u00e9rence entre ta g\u00e9n\u00e9ration et la pr\u00e9c\u00e9dente ? <\/strong><\/p>\n<p>\u00ab Ma g\u00e9n\u00e9ration ne croit plus dans la paix. La vieille g\u00e9n\u00e9ration avait plac\u00e9 ses espoirs dans la communaut\u00e9 internationale et dans le droit international. Ils ont renonc\u00e9 \u00e0 tout pour la solution \u00e0 deux \u00c9tats. Sans r\u00e9sultat, avec tout le respect pour les prisonniers et les martyrs. Notre g\u00e9n\u00e9ration n\u2019est pas la m\u00eame. C\u2019est notre terre. Nous nous battons pour toute la <em>Palestine<\/em>. Mais nous n\u2019avons pas confiance dans la communaut\u00e9 internationale et nous ne sommes pas attach\u00e9s non plus aux partis politiques ou organisations <em>palestiniens<\/em>. Nous luttons pour un monde au sein duquel toute la <em>Palestine <\/em>sera lib\u00e9r\u00e9e. \u00bb<\/p>\n<p><strong>Tu ne te d\u00e9finis pas comme une faiseuse de paix mais comme une combattante de la libert\u00e9. Pourquoi cette d\u00e9finition est-elle importante pour toi ? <\/strong><\/p>\n<p>\u00ab Si je me d\u00e9finissais comme une faiseuse de paix, je me pr\u00e9senterais comme une victime et je demanderais de l\u2019empathie. Les victimes, ce sont les <em>sionistes<\/em> de 18 ans qui vivent dans les colonies, qui ont une arme et \u00e9prouvent plein de haine \u00e0 notre endroit. Je me d\u00e9finis comme une combattante de la libert\u00e9 parce que je veux inviter les gens \u00e0 \u00eatre une composante de ce combat. Il n\u2019y a pas de paix dans le monde. Et je ne suis pas non plus encline au pardon. Comment puis-je vivre \u00e0 c\u00f4t\u00e9 du soldat qui m\u2019a arr\u00eat\u00e9e ? Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance. \u00bb<\/p>\n<p style=\"text-align: center;\">\u00b0\u00b0\u00b0\u00b0\u00b0<\/p>\n<p>Article publi\u00e9 le 22 septembre sur <a href=\"https:\/\/www.demorgen.be\/nieuws\/de-palestijnse-die-de-wereld-rondging-toen-ze-een-israelische-soldaat-sloeg-we-willen-jullie-tranen-niet~b978fb1c\/?referrer=https%3A%2F%2Fwww.google.com%2F\" target=\"_blank\" rel=\"noopener\">De Morgen<\/a><br \/>Traduction : Jean-Marie Fl\u00e9mal, <a href=\"https:\/\/charleroi-pourlapalestine.be\/\">Charleroi pour la Palestine<\/a><\/p>\n<p style=\"text-align: center;\">\u00b0\u00b0\u00b0\u00b0\u00b0<\/p>\n<p>(*) Lorsque nous avons rencontr\u00e9 <strong>Ahed Tamimi<\/strong> au festival ManiFiesta, nous lui avons parl\u00e9 de la <a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/03\/samedi-29-octobre-2022-marche-du-retour-et-de-la-liberation-a-bruxelles\/\"><strong>Marche pour le Retour et la Lib\u00e9ration<\/strong><\/a>, qui aura lieu \u00e0 Bruxelles, \u00e0 l&rsquo;appel de <strong>Masar Badil,<\/strong> le <strong>Mouvement palestinien de la voie alternative r\u00e9volutionnaire. <\/strong>Ahed a tenu \u00e0 affirmer son soutien en photo.<\/p>\n<p>La Marche aura lieu <strong>samedi 29 octobre \u00e0 Bruxelles<\/strong>. <span class=\"gvxzyvdx aeinzg81 t7p7dqev gh25dzvf exr7barw b6ax4al1 gem102v4 ncib64c9 mrvwc6qr sx8pxkcf f597kf1v cpcgwwas m2nijcs8 hxfwr5lz k1z55t6l oog5qr5w tes86rjd pbevjfx6 ztn2w49o\" dir=\"auto\">Elle partira \u00e0 14 h, square Lumumba (porte de Namur) pour se rendre devant le parlement europ\u00e9en. <\/span><\/p>\n<p><span class=\"gvxzyvdx aeinzg81 t7p7dqev gh25dzvf exr7barw b6ax4al1 gem102v4 ncib64c9 mrvwc6qr sx8pxkcf f597kf1v cpcgwwas m2nijcs8 hxfwr5lz k1z55t6l oog5qr5w tes86rjd pbevjfx6 ztn2w49o\" dir=\"auto\">La marche et le rassemblement devant le parlement europ\u00e9en seront le point culminant d&rsquo;une <strong>semaine pour la Lib\u00e9ration de la Palestine<\/strong>. Plus d&rsquo;infos bient\u00f4t.<\/span><\/p>\n<p>Trouvez ici une belle pr\u00e9sentation en vid\u00e9o de <strong>Masar Badil<\/strong> :<\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" title=\"Le Mouvement alternatif pour la voie r\u00e9volutionnaire palestinienne est fond\u00e9 !\" src=\"https:\/\/www.youtube.com\/embed\/eti6IblDU4E?start=6&amp;feature=oembed&amp;wmode=opaque\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\" width=\"500\" height=\"281\" frameborder=\"0\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ahed Tamimi : \u00ab\u00a0Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.\u00a0\u00bb<\/p>\n","protected":false},"author":1,"featured_media":44341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[90,361,192,13,25],"tags":[],"class_list":["post-44337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bds","category-jeunes","category-palestine","category-les-prisionners-palestiniens","category-la-resistance-palestinienne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb<\/title>\n<meta name=\"description\" content=\"Ahed Tamimi : &quot;Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/\"},\"author\":{\"name\":\"admin1873\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\"},\"headline\":\"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb\",\"datePublished\":\"2022-09-24T11:35:34+00:00\",\"dateModified\":\"2022-09-24T11:57:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/\"},\"wordCount\":1008,\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20220924_095343.jpg\",\"articleSection\":[\"Boycott \\\"Isra\u00ebl\\\"\",\"jeunes\",\"Palestine\",\"Prisonniers\",\"R\u00e9sistance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/\",\"name\":\"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20220924_095343.jpg\",\"datePublished\":\"2022-09-24T11:35:34+00:00\",\"dateModified\":\"2022-09-24T11:57:44+00:00\",\"description\":\"Ahed Tamimi : \\\"Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20220924_095343.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/IMG_20220924_095343.jpg\",\"width\":2136,\"height\":1579,\"caption\":\"dav\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2022\\\/09\\\/24\\\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\",\"name\":\"admin1873\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/author\\\/admin1873\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb","description":"Ahed Tamimi : \"Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#article","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/"},"author":{"name":"admin1873","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa"},"headline":"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb","datePublished":"2022-09-24T11:35:34+00:00","dateModified":"2022-09-24T11:57:44+00:00","mainEntityOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/"},"wordCount":1008,"publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/09\/IMG_20220924_095343.jpg","articleSection":["Boycott \"Isra\u00ebl\"","jeunes","Palestine","Prisonniers","R\u00e9sistance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/","name":"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#primaryimage"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/09\/IMG_20220924_095343.jpg","datePublished":"2022-09-24T11:35:34+00:00","dateModified":"2022-09-24T11:57:44+00:00","description":"Ahed Tamimi : \"Notre terre a \u00e9t\u00e9 accapar\u00e9e dans la violence, la seule fa\u00e7on de lib\u00e9rer notre terre et de la r\u00e9cup\u00e9rer, c\u2019est de recourir \u00e0 la r\u00e9sistance.\"","breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#primaryimage","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/09\/IMG_20220924_095343.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/09\/IMG_20220924_095343.jpg","width":2136,"height":1579,"caption":"dav"},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2022\/09\/24\/ahed-tamimi-la-seule-facon-de-liberer-notre-terre-cest-la-resistance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Ahed Tamimi : \u00ab La seule fa\u00e7on de lib\u00e9rer notre terre, c\u2019est la r\u00e9sistance \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]},{"@type":"Person","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa","name":"admin1873","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/author\/admin1873\/"}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/44337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/comments?post=44337"}],"version-history":[{"count":0,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/44337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media\/44341"}],"wp:attachment":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media?parent=44337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories?post=44337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/tags?post=44337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}