{"id":72010,"date":"2024-05-17T09:48:33","date_gmt":"2024-05-17T07:48:33","guid":{"rendered":"https:\/\/charleroi-pourlapalestine.be\/?p=72010"},"modified":"2024-05-17T09:48:42","modified_gmt":"2024-05-17T07:48:42","slug":"les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza","status":"publish","type":"post","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/","title":{"rendered":"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza"},"content":{"rendered":"<p>Ces derniers jours, dans la ville de Gaza, compl\u00e8tement ferm\u00e9e, Isra\u00ebl a soumis les Palestiniens \u00e0 certaines des attaques les plus s\u00e9v\u00e8res qu&rsquo;ils aient subies. La violence a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi une population d\u00e9j\u00e0 passablement \u00e9puis\u00e9e et traumatis\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_72011\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-72011\" class=\"wp-image-72011 size-full\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg\" alt=\"11 mai 2024. Le camp de r\u00e9fugi\u00e9s d'al-Maghazi (dans la partie centrale de Gaza) apr\u00e8s une frappe a\u00e9rienne isra\u00e9lienne. \" width=\"800\" height=\"533\" srcset=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg 800w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza-300x200.jpg 300w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-72011\" class=\"wp-caption-text\"><strong>11 mai 2024. Le camp de r\u00e9fugi\u00e9s d&rsquo;al-Maghazi (dans la partie centrale de Gaza) apr\u00e8s une frappe a\u00e9rienne isra\u00e9lienne<\/strong>. (Photo : Omar Ashtawy \/ APA images)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Maureen Clare Murphy<\/strong>, 14 mai 2024<\/p>\n<p>Environ un cinqui\u00e8me de la population de Gaza (2,3 millions d&rsquo;habitants) a \u00e9t\u00e9 d\u00e9plac\u00e9e, une fois de plus, cette derni\u00e8re semaine, d&rsquo;apr\u00e8s l&rsquo;ONU.<\/p>\n<p>Entre-temps, la p\u00e9nurie de carburant menace les services de sant\u00e9 et <em>\u00ab provoque une augmentation des maladies infectieuses \u00bb,<\/em> en raison de l&rsquo;acc\u00e8s limit\u00e9 \u00e0 des installations sanitaires, a d\u00e9clar\u00e9 l&rsquo;ONU.<\/p>\n<p>L&rsquo;ONG Oxfam a expliqu\u00e9 lundi que,<\/p>\n<blockquote><p>\u00ab depuis octobre, les attaques isra\u00e9liennes ont provoqu\u00e9 pour au moins 210 millions de USD de d\u00e9g\u00e2ts aux infrastructures d&rsquo;eau et d&rsquo;assainissement de Gaza \u00bb.<\/p><\/blockquote>\n<p>https:\/\/x.com\/AbujomaaGaza\/status\/1789629198266446246?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1789629198266446246%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<p>Le risque d&rsquo;\u00e9pid\u00e9mie est en hausse du fait que l&rsquo;invasion de Rafah est <em>\u00ab un cocktail meurtrier compos\u00e9 de surpeuplement, d&rsquo;eaux us\u00e9es et de famine \u00bb<\/em>, a ajout\u00e9 Oxfam.<\/p>\n<blockquote><p>\u00ab Le personnel d&rsquo;Oxfam \u00e0 Gaza a \u00e9voqu\u00e9 des monceaux de d\u00e9chets humains et des rivi\u00e8res d&rsquo;eaux us\u00e9es dans les rues, entre lesquels les gens doivent sauter pour se d\u00e9placer \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 l&rsquo;ONG.<\/p>\n<blockquote><p>\u00ab Le personnel fait \u00e9galement \u00e9tat de gens oblig\u00e9s de boire de l&rsquo;eau malsaine et d&rsquo;enfants piqu\u00e9s par les insectes qui essaiment autour des eaux us\u00e9es. \u00bb<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h3>Les passages restent ferm\u00e9s<\/h3>\n<p>Le passage de Rafah est rest\u00e9 ferm\u00e9 lundi et il n&rsquo;y a \u00ab\u00a0<em>plus d&rsquo;acc\u00e8s s\u00e9curis\u00e9 et viable sur le plan logistique au passage de Kerem Shalom<\/em> \u00bb, a fait savoir l&rsquo;ONU. Ces deux passages constituaient le hub des op\u00e9rations humanitaires absolument n\u00e9cessaires \u00e0 Gaza et Isra\u00ebl les a ferm\u00e9s tous deux la semaine derni\u00e8re.<\/p>\n<p>L&rsquo;arm\u00e9e isra\u00e9lienne a affirm\u00e9 que des acheminements d&rsquo;aide \u00e9taient entr\u00e9s \u00e0 Gaza par le check-point d&rsquo;Erez jeudi et par celui de Zikim dimanche et que, dimanche \u00e9galement, 266 000 litres de carburant \u00e9taient entr\u00e9s \u00e0 Gaza par Kerem Shalom.<\/p>\n<blockquote><p>\u00ab Bien que du carburant et des cargaisons de vivres soient entr\u00e9s \u00e0 Gaza ces deux derniers jours, les livraisons d&rsquo;aide restent largement insuffisantes \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 lundi le Bureau de l&rsquo;ONU pour la coordination des affaires humanitaires (OCHA).<\/p>\n<blockquote><p>\u00ab Les conditions dominantes pourraient aggraver les niveaux d\u00e9j\u00e0 catastrophiques de la famine \u00e0 laquelle est confront\u00e9e la population \u00bb,<\/p><\/blockquote>\n<p>a poursuivi l&rsquo;OCHA, faisant remarquer que les efforts pour accro\u00eetre la stabilisation alimentaire ont \u00e9t\u00e9 <em>\u00ab annihil\u00e9s \u00e0 Rafah \u00bb<\/em>, en raison des ordres d&rsquo;\u00e9vacuation et de l&rsquo;escalade militaire impos\u00e9s par Isra\u00ebl.<\/p>\n<p>On rapporte que pr\u00e8s de 200 Palestiniens ont \u00e9t\u00e9 tu\u00e9s \u00e0 Gaza entre le 9 et le 13 mai, portant \u00e0 plus de 35 000 le nombre de Palestiniens tu\u00e9s dans le territoire depuis le 7 octobre. 78 800 autres ont \u00e9t\u00e9 bless\u00e9s et environ 10 000 sont port\u00e9s manquants, rest\u00e9s entre autres sous les d\u00e9combres, ont fait savoir les autorit\u00e9s locales de Gaza.<\/p>\n<p>Cinq soldats isra\u00e9liens, dit-on, ont \u00e9t\u00e9 tu\u00e9s \u00e0 Gaza entre le 10 et le 13 mai, ce qui porte \u00e0 272 le nombre de soldats tu\u00e9s \u00e0 Gaza ou le long de la fronti\u00e8re depuis le d\u00e9but de l&rsquo;offensive terrestre d&rsquo;Isra\u00ebl fin octobre.<\/p>\n<p>Des combats intenses ont eu lieu autour de la ville de Gaza, ces derniers jours.<\/p>\n<p>Vendredi, l&rsquo;Euro-Med Human Rights Monitor a d\u00e9clar\u00e9 que les <em>\u00ab tueries al\u00e9atoires \u00bb<\/em> dans le quartier de Zaytoun, dans l&rsquo;est de Rafah, l&rsquo;une des zones les plus dens\u00e9ment peupl\u00e9es de l&rsquo;enclave, visaient \u00e0 chasser les r\u00e9sidents et \u00e0 d\u00e9truire la ville.<\/p>\n<p>Des drones quadricopt\u00e8res isra\u00e9liens ont cibl\u00e9 et tu\u00e9 des civils \u00e0 Zaytoun et l&rsquo;arm\u00e9e a attaqu\u00e9 des personnes d\u00e9plac\u00e9es qui s&rsquo;\u00e9taient r\u00e9fugi\u00e9s dans une \u00e9cole, \u00ab<em> ce qui s&rsquo;est traduit par de nombreuses victimes \u00bb<\/em>, selon l&rsquo;Euro-Med Monitor.<\/p>\n<p>L&rsquo;organisation a d\u00e9clar\u00e9 qu&rsquo;Isra\u00ebl \u00e9tendait ses pr\u00e9tendues zones tampons<\/p>\n<blockquote><p>\u00ab afin de renforcer sa position militaire dans l&rsquo;axe de Netzarim \u00bb<\/p><\/blockquote>\n<p>via lequel il contr\u00f4le le mouvement des Palestiniens entre le nord et le sud de l&rsquo;enclave.<\/p>\n<p>&nbsp;<\/p>\n<h3>Isra\u00ebl pilonne Jabaliya<\/h3>\n<p>Dimanche, des chars isra\u00e9liens sont retourn\u00e9s dans le nord de Gaza, que son arm\u00e9e avait d\u00e9j\u00e0 r\u00e9duit en ruines et o\u00f9, en janvier, il pr\u00e9tendait avoir d\u00e9mantel\u00e9 les forces combattantes du Hamas dans la zone.<\/p>\n<p>Samedi, Isra\u00ebl a ordonn\u00e9 aux personnes d&rsquo;\u00e9vacuer les zones de Jabaliya, de son camp de r\u00e9fugi\u00e9s et de Beit Lahiya, dans le nord de Gaza.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\u201cAnyone who remains in these areas will endanger his life and that of his family members\u201d.  Ironically, they\u2019re addressing them as \u201cto the Displaced in Jabalia\u201d. <\/p>\n<p>Israel on Saturday imposed the immediate expulsion of new areas in Rafah, Jabalia and Beit Lahia in the North. <a href=\"https:\/\/t.co\/HDrv5mANd7\">pic.twitter.com\/HDrv5mANd7<\/a><\/p>\n<p>&mdash; Hanine Hassan \u062d\u0646\u064a\u0646 (@Hanine09) <a href=\"https:\/\/x.com\/Hanine09\/status\/1789274288815509653?ref_src=twsrc%5Etfw\">May 11, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n<p>Un survivant palestinien a dit que les corps de plus de 40 femmes et enfants avaient \u00e9t\u00e9 retrouv\u00e9s sous les ruines d&rsquo;un immeuble r\u00e9sidentiel ras\u00e9 par une frappe a\u00e9rienne isra\u00e9lienne \u00e0 Beit Lahiya. Les mains des enfants \u00e9taient toujours jointes les unes aux autres au moment o\u00f9 leurs corps ont \u00e9t\u00e9 retir\u00e9s des d\u00e9combres, a expliqu\u00e9 l&rsquo;homme \u00e0 Al Jazeera.<\/p>\n<p>Les Palestiniens de la zone ont rapport\u00e9 plus de cent frappes a\u00e9riennes contre Jabaliya durant le week-end.<\/p>\n<blockquote><p>\u00ab Nous pensions que les premiers jours [de la guerre] \u00e9taient le pire de tout, puis nous nous sommes dit que le pire \u00e9tait la faim, mais ces bombardements ne ressemblent \u00e0 rien de ce que nous avons d\u00e9j\u00e0 v\u00e9cu \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 dimanche Hossam Shabat, un journaliste dans le nord de Gaza.<\/p>\n<p>https:\/\/x.com\/gazamom\/status\/1789381669939491027?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1789381669939491027%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<p>Lundi, les forces isra\u00e9liennes ont assi\u00e9g\u00e9 des \u00e9coles de l&rsquo;UNRWA, dans l&rsquo;est du camp de r\u00e9fugi\u00e9s de Jabaliya, affirme le Centre palestinien pour les droits humains (CPDH). Des milliers de personnes avaient cherch\u00e9 refuge dans les \u00e9coles administr\u00e9es par l&rsquo;UNRWA, l&rsquo;Agence de l&rsquo;ONU pour les r\u00e9fugi\u00e9s palestiniens, apr\u00e8s avoir \u00e9t\u00e9 d\u00e9plac\u00e9es d&rsquo;autres zones de la partie nord de Gaza.<\/p>\n<p>Les chars isra\u00e9liens positionn\u00e9s \u00e0 l&rsquo;entr\u00e9e des \u00e9coles ont tir\u00e9 des obus d&rsquo;artillerie et <em>\u00ab des drones quadricopt\u00e8res tiraient sur tout ce qui bougeait \u00bb<\/em>, dit encore l&rsquo;organisation de d\u00e9fense des droits.<\/p>\n<blockquote><p>\u00ab Les personnes d\u00e9plac\u00e9es ont \u00e9t\u00e9 forc\u00e9es de quitter les \u00e9coles au plus fort des tirs et un certain nombre d&rsquo;entre elles ont \u00e9t\u00e9 arr\u00eat\u00e9es. \u00bb<\/p><\/blockquote>\n<p>Au moins 20 Palestiniens ont \u00e9t\u00e9 tu\u00e9s dans la zone et on dit que plusieurs personnes ont \u00e9t\u00e9 pi\u00e9g\u00e9es sous les d\u00e9combres d&rsquo;une maison cibl\u00e9e par les frappes a\u00e9riennes \u00e0 Jabaliya.<\/p>\n<p>La Soci\u00e9t\u00e9 du Croissant-Rouge de Palestine (SCRP) a publi\u00e9 une vid\u00e9o montrant Ali Khalil, l&rsquo;un de ses param\u00e9dicaux b\u00e9n\u00e9voles, s&rsquo;\u00e9croulant de chagrin apr\u00e8s que les corps de ses petits-enfants ont \u00e9t\u00e9 amen\u00e9s \u00e0 l&rsquo;une des antennes m\u00e9dicales de l&rsquo;organisation humanitaire \u00e0 Jabaliya :<\/p>\n<p>https:\/\/x.com\/gazamom\/status\/1789381669939491027?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1789381669939491027%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<p>Les Brigades Qassam, l&rsquo;aile arm\u00e9e du Hamas, ont d\u00e9clar\u00e9 lundi que leurs combattants avaient affront\u00e9 les forces ennemies \u00e0 Zaytoun, pr\u00e8s de la ville de Gaza, qu&rsquo;elles avaient touch\u00e9 des chars Merkava \u00e0 l&rsquo;est du camp de r\u00e9fugi\u00e9s de Jabaliya, dans le nord de Gaza et qu&rsquo;elles avaient \u00e9galement tir\u00e9 des roquettes vers Isra\u00ebl depuis la zone de Jabaliya.<\/p>\n<p>&nbsp;<\/p>\n<h3>Rafah<\/h3>\n<p>Les Brigades Qassam ont \u00e9galement d\u00e9clar\u00e9 qu&rsquo;elles avaient cibl\u00e9 des forces terrestres isra\u00e9liennes pr\u00e8s du passage de Rafah, dans le sud de Gaza. Apr\u00e8s s&rsquo;\u00eatre empar\u00e9 de son contr\u00f4le la semaine derni\u00e8re, Isra\u00ebl a transform\u00e9 le passage de Rafah \u2013 qui, avant la guerre, \u00e9tait le principal point de sortie et d&rsquo;entr\u00e9e des gens \u00e0 Gaza \u2013 en base militaire :<\/p>\n<p>https:\/\/x.com\/Sinaifhr\/status\/1789632318702780452?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1789632318702780452%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<p>L&rsquo;organisation \u00e9gyptienne Sinai for Human Rights (Le Sina\u00ef pour les droits humains) a d\u00e9clar\u00e9 que des routiers transportant de l&rsquo;aide avaient rapport\u00e9 que d&rsquo;importantes quantit\u00e9s de nourriture avaient \u00e9t\u00e9 g\u00e2ch\u00e9es en attendant d&rsquo;\u00eatre d\u00e9charg\u00e9es dans le sud de Gaza.<\/p>\n<p>Les autorit\u00e9s isra\u00e9liennes ont d\u00e9clar\u00e9 que les roquettes tir\u00e9es depuis Rafah vendredi soir avaient atterri \u00e0 Bir al-Saba, la ville cosmopolite du d\u00e9sert purg\u00e9e de ses r\u00e9sidents palestiniens en 1948 et connue d\u00e9sormais sous le nom h\u00e9breu de Beersheva.<\/p>\n<p>Isra\u00ebl a ordonn\u00e9 la semaine derni\u00e8re que les quartiers de la partie orientale de Rafah soient \u00e9vacu\u00e9s et, d\u00e8s lundi, quelque 360 000 Palestiniens avaient fui la zone, selon l&rsquo;UNRWA.<\/p>\n<p>Mais bien des Palestiniens \u00e0 Rafah, d\u00e9plac\u00e9s d&rsquo;autres zones de Gaza, n&rsquo;ont pas les moyens de s&rsquo;en aller et sont d\u00e9sormais priv\u00e9s d&rsquo;acc\u00e8s aux soins de sant\u00e9 et \u00e0 l&rsquo;aide humanitaire.<\/p>\n<p>Philippe Lazzarini, le directeur de l&rsquo;UNRWA, a dit que la plupart des gens \u00e0 Gaza <em>\u00ab se sont d\u00e9plac\u00e9s \u00e0 de multiples reprises : en moyenne, une fois par mois \u00bb<\/em>, cherchant d\u00e9sesp\u00e9r\u00e9ment \u00ab une s\u00e9curit\u00e9 qu&rsquo;ils n&rsquo;ont jamais trouv\u00e9e \u00bb.<\/p>\n<p>Balakrishnan Rajagopal, le rapporteur sp\u00e9cial de l&rsquo;ONU sur le droit \u00e0 un logement ad\u00e9quat, a d\u00e9clar\u00e9 :<\/p>\n<blockquote><p>\u00ab En plus de trente ans d&rsquo;\u00e9tude et d&rsquo;engagement avec les communaut\u00e9s affect\u00e9es par des d\u00e9placements, je n&rsquo;ai encore jamais vu une atrocit\u00e9 aussi choquante que celle-ci. \u00bb<\/p><\/blockquote>\n<p>Les responsables isra\u00e9liens et am\u00e9ricains ont caract\u00e9ris\u00e9 l&rsquo;offensive \u00e0 Rafah comme une op\u00e9ration plus limit\u00e9e. Mais le Centre palestinien pour les droits humains (CPDH) a d\u00e9clar\u00e9 dimanche que ce qui se passait l\u00e0 \u00ab<em> \u00e9tait une attaque militaire \u00e0 grande \u00e9chelle \u00bb.<\/em><\/p>\n<p>L&rsquo;organisation a dit qu&rsquo;au moins 116 Palestiniens, dont 22 femmes et 38 enfants, avaient \u00e9t\u00e9 tu\u00e9s depuis le d\u00e9but de l&rsquo;offensive terrestre isra\u00e9lienne \u00e0 Rafah sept jours plus t\u00f4t. D&rsquo;autres encore ont \u00e9t\u00e9 port\u00e9s manquants, a ajout\u00e9 le CPDH.<\/p>\n<p>L&rsquo;organisation a encore dit qu&rsquo;Isra\u00ebl avait accru le nombre de ses attaques sans discrimination dans les zones qui n&rsquo;avaient pas re\u00e7u d&rsquo;ordre d&rsquo;\u00e9vacuation, et que plus de 50 Palestiniens avaient \u00e9t\u00e9 tu\u00e9s dans la partie centrale de Gaza, parmi lesquels un m\u00e9decin et son fils.<\/p>\n<p>https:\/\/x.com\/RamAbdu\/status\/1789398029549617603?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1789398029549617603%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00ab Isra\u00ebl poursuit sans ralentir le moins du monde sa campagne militaire g\u00e9nocidaire contre le peuple palestinien \u00e0 Gaza \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 le CPDH.<\/p>\n<blockquote><p>\u00ab Nous r\u00e9it\u00e9rons notre appel en faveur d&rsquo;un cessez-le-feu imm\u00e9diat. Ce g\u00e9nocide doit cesser \u00e0 l&rsquo;instant ! \u00bb<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>Des travailleurs de l&rsquo;ONU tu\u00e9s<\/strong><\/p>\n<p>Lundi, apr\u00e8s avoir fui Rafah, un employ\u00e9 de 53 ans de l&rsquo;UNRWA a \u00e9t\u00e9 tu\u00e9 par une frappe a\u00e9rienne isra\u00e9lienne \u00e0 Deir al-Balah, dans le centre de la bande de Gaza.<\/p>\n<p>Sa mort porte \u00e0 189 le nombre de membres de l&rsquo;UNRWA tu\u00e9s \u00e0 Gaza depuis le 7 octobre.<\/p>\n<p>Lundi matin, un membre de la s\u00fbret\u00e9 et de la s\u00e9curit\u00e9 des Nations unies a \u00e9t\u00e9 tu\u00e9 et un autre gri\u00e8vement bless\u00e9 quand leur v\u00e9hicule de l&rsquo;ONU s&rsquo;est retrouv\u00e9 sous les tirs alors qu&rsquo;il se rendait vers l&rsquo;H\u00f4pital europ\u00e9en de Gaza, pr\u00e8s de Khan Younis, au nord de Rafah.<\/p>\n<p>Le personnel m\u00e9dical de l&rsquo;H\u00f4pital kowe\u00eftien de Rafah a re\u00e7u une ordre d&rsquo;\u00e9vacuation d&rsquo;Isra\u00ebl, a rapport\u00e9 lundi l&rsquo;ONG britannique Medical Aid for Palestinians (MAP).<\/p>\n<blockquote><p>\u00ab C&rsquo;\u00e9tait l&rsquo;un des derniers h\u00f4pitaux restants \u00e0 Rafah et il n&rsquo;avait plus que 16 lits disponibles environ pour plus d&rsquo;un million de personnes qui s&rsquo;\u00e9taient r\u00e9fugi\u00e9es dans le secteur \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 MAP.<\/p>\n<blockquote><p>\u00ab Si l&rsquo;h\u00f4pital est forc\u00e9 de s&rsquo;arr\u00eater, cela pourrait signifier l&rsquo;effondrement complet du syst\u00e8me d\u00e9j\u00e0 tr\u00e8s limit\u00e9 des soins de sant\u00e9 \u00e0 Rafah. \u00bb<\/p><\/blockquote>\n<p>L&rsquo;ONG a ajout\u00e9 que l&rsquo;H\u00f4pital europ\u00e9en de Gaza \u00e9tait tomb\u00e9 \u00e0 court de carburant suite \u00e0 la fermeture par Isra\u00ebl des passages dans le sud de Gaza et apr\u00e8s qu&rsquo;Isra\u00ebl avait coup\u00e9 l&rsquo;approvisionnement du territoire en \u00e9lectricit\u00e9 d\u00e9but octobre.<\/p>\n<p>La fermeture du passage de Rafah<\/p>\n<blockquote><p>\u00ab continue de signifier que les patients ne peuvent \u00eatre \u00e9vacu\u00e9s m\u00e9dicalement \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 MAP.<\/p>\n<blockquote><p>\u00ab Nous nous attendons \u00e0 ce qu&rsquo;il en r\u00e9sulte plus de morts inutiles de patients encore, puisqu&rsquo;ils ne sont pas \u00e0 m\u00eame d&rsquo;acc\u00e9der \u00e0 des traitements appropri\u00e9s \u00e0 Gaza. \u00bb<\/p><\/blockquote>\n<p>Volker Turk, le haut-commissaire de l&rsquo;ONU pour les droits humains, a d\u00e9clar\u00e9 lundi que les ordres d&rsquo;\u00e9vacuation \u00e0 Rafah ne peuvent se conformer aux mesures provisoires l\u00e9galement contraignantes ordonn\u00e9es par la Cour internationale de Justice.<\/p>\n<p>Ces mesures comprenaient des demandes qu&rsquo;Isra\u00ebl garantisse la livraison sans entrave de l&rsquo;aide humanitaire et des services de base \u00e0 Gaza.<\/p>\n<p>Vendredi, Volker Turk a dit qu&rsquo;il d\u00e9plorait<\/p>\n<blockquote><p>\u00ab tout acte hostile qui mettait en danger l&rsquo;entr\u00e9e et la distribution \u00e0 Gaza de l&rsquo;aide humanitaire d\u00e9sesp\u00e9r\u00e9ment n\u00e9cessaire \u00bb.<\/p>\n<p>\u00ab Les quelques rares passages terrestres vers Gaza servent de ligne vitale pour l&rsquo;approvisionnement en vivres, en m\u00e9dicaments, en carburant et autres marchandises n\u00e9cessaires qui doivent pouvoir atteindre une population d\u00e9sesp\u00e9r\u00e9e et terrifi\u00e9e \u00bb,<\/p><\/blockquote>\n<p>a-t-il ajout\u00e9.<\/p>\n<p>Lundi, une vid\u00e9o circulait sur les m\u00e9dias sociaux montrant des Isra\u00e9liens en Cisjordanie en train de vandaliser la cargaison d&rsquo;un camion d&rsquo;aide qui faisait route vers Gaza :<\/p>\n<p>https:\/\/x.com\/BarakRavid\/status\/1790015282490101762?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1790015282490101762%7Ctwgr%5E92ad6104aba01b466ed80eb421e40e9e6b5e533e%7Ctwcon%5Es1_&#038;ref_url=https%3A%2F%2Felectronicintifada.net%2Fblogs%2Fmaureen-clare-murphy%2Fisraeli-attacks-newly-displace-one-fifth-gazas-population<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00ab Cela a dur\u00e9 des heures, en pr\u00e9sence des forces isra\u00e9liennes qui ne sont jamais intervenues \u00bb,<\/p><\/blockquote>\n<p>a d\u00e9clar\u00e9 B&rsquo;Tselem, une organisation isra\u00e9lienne de d\u00e9fense des droits humains.<\/p>\n<p>B\u2019Tselem d&rsquo;ajouter que \u00ab<em> cela va \u00e0 l&rsquo;encontre \u00bb<\/em> des ordres de la Cour internationale de Justice.<\/p>\n<p style=\"text-align: center;\">*****<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-45540 size-full\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/10\/Maureen-Clare-Murphy-e1665914569514.jpg\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" srcset=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/10\/Maureen-Clare-Murphy-e1665914569514.jpg 150w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2022\/10\/Maureen-Clare-Murphy-e1665914569514-80x80.jpg 80w\" alt=\"\" width=\"150\" height=\"150\"><a tabindex=\"-1\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/tag\/maureen-clare-murphy\/\">Maureen Clare Murphy<\/a><\/strong> est r\u00e9dactrice en chef de <a tabindex=\"-1\" href=\"https:\/\/electronicintifada.net\/blogs\/maureen-clare-murphy\/craig-mokhiber-moving-world-palestinian-rights\" target=\"_blank\" rel=\"noopener\">The Electronic Intifada.<\/a><\/p>\n<div class=\"pf-content\">\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ******<br \/>\nPubli\u00e9 le 14 mai 2024 sur <a href=\"https:\/\/electronicintifada.net\/blogs\/maureen-clare-murphy\/israeli-attacks-newly-displace-one-fifth-gazas-population\" target=\"_blank\" rel=\"noopener\"><strong>The Electronic Intifada<\/strong><\/a><br \/>\nTraduction : Jean-Marie Fl\u00e9mal, <strong><a tabindex=\"-1\" href=\"http:\/\/www.pourlapalestine.be\/\">Charleroi pour la Palestine<\/a><\/strong><\/p>\n<\/div>\n<p><strong><br \/>\nNDLR : Afin de pouvoir lire les \u201ctweets\u201d et vid\u00e9os repris dans l\u2019article, ouvrez un compte Twitter (X)<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La violence des bombardements a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi une population d\u00e9j\u00e0 passablement \u00e9puis\u00e9e et traumatis\u00e9e. <\/p>\n","protected":false},"author":1,"featured_media":72011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6,344,956],"tags":[],"class_list":["post-72010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaza","category-genocide","category-rafah"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza<\/title>\n<meta name=\"description\" content=\"La violence des bombardements a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi la population de Gaza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/\"},\"author\":{\"name\":\"admin1873\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\"},\"headline\":\"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza\",\"datePublished\":\"2024-05-17T07:48:33+00:00\",\"dateModified\":\"2024-05-17T07:48:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/\"},\"wordCount\":2696,\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg\",\"articleSection\":[\"Gaza\",\"G\u00e9nocide\",\"Rafah\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/\",\"name\":\"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg\",\"datePublished\":\"2024-05-17T07:48:33+00:00\",\"dateModified\":\"2024-05-17T07:48:42+00:00\",\"description\":\"La violence des bombardements a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi la population de Gaza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/05\\\/17\\\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\",\"name\":\"admin1873\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/author\\\/admin1873\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza","description":"La violence des bombardements a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi la population de Gaza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#article","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/"},"author":{"name":"admin1873","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa"},"headline":"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza","datePublished":"2024-05-17T07:48:33+00:00","dateModified":"2024-05-17T07:48:42+00:00","mainEntityOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/"},"wordCount":2696,"publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg","articleSection":["Gaza","G\u00e9nocide","Rafah"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/","name":"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#primaryimage"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg","datePublished":"2024-05-17T07:48:33+00:00","dateModified":"2024-05-17T07:48:42+00:00","description":"La violence des bombardements a provoqu\u00e9 une nouvelle vague de d\u00e9placement massif parmi la population de Gaza","breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#primaryimage","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/05\/Le-camp-de-refugies-dal-Maghazi-dans-la-partie-centrale-de-Gaza.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/05\/17\/les-attaques-israeliennes-deplacent-a-nouveau-un-cinquieme-de-la-population-de-gaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Les attaques isra\u00e9liennes d\u00e9placent \u00e0 nouveau un cinqui\u00e8me de la population de Gaza"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]},{"@type":"Person","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa","name":"admin1873","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/author\/admin1873\/"}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/72010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/comments?post=72010"}],"version-history":[{"count":0,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/72010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media\/72011"}],"wp:attachment":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media?parent=72010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories?post=72010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/tags?post=72010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}