{"id":73646,"date":"2024-07-01T16:07:53","date_gmt":"2024-07-01T14:07:53","guid":{"rendered":"https:\/\/charleroi-pourlapalestine.be\/?p=73646"},"modified":"2024-07-01T16:08:08","modified_gmt":"2024-07-01T14:08:08","slug":"gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent","status":"publish","type":"post","link":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/","title":{"rendered":"Gaza : les buts affirm\u00e9s d&rsquo;Isra\u00ebl ne sont qu&rsquo;un mensonge grandiloquent"},"content":{"rendered":"<p>Lorsqu&rsquo;on se trouve \u00e0 Gaza et qu&rsquo;on voit les destructions de tout pr\u00e8s, la conclusion la plus \u00e9vidente est que les buts affirm\u00e9s d&rsquo;Isra\u00ebl ne sont qu&rsquo;un mensonge grandiloquent, du m\u00eame tonneau que <em>\u00ab un peuple sans terre pour une terre sans peuple \u00bb,<\/em> emball\u00e9 et vendu au monde entier.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_73649\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-73649\" class=\"wp-image-73649 size-full\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg\" alt=\"\u00c0 chaque heure, \u00e0 Gaza, Isra\u00ebl d\u00e9truite douze b\u00e2timents \" width=\"800\" height=\"600\" srcset=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg 800w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza-300x225.jpg 300w, https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-73649\" class=\"wp-caption-text\"><strong>\u00c0 chaque heure, \u00e0 Gaza, douze b\u00e2timents sont d\u00e9truits<\/strong>. (Photo : Hadi Daoud \/ APA images)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/tag\/susan-abulhawa\/\" target=\"_blank\" rel=\"noopener\"><strong>Susan Abulhawa<\/strong><\/a>, 27 juin 2024<\/p>\n<p>Les maths sont tr\u00e8s utiles afin de prouver ce que je dis.<\/p>\n<p>Et voici donc quelques chiffres pour commencer.<\/p>\n<p>&nbsp;<\/p>\n<h3>Destruction de b\u00e2timents<\/h3>\n<p>\u2022<strong>En avril 2024, quelque 360 000 b\u00e2timents ont \u00e9t\u00e9<\/strong><a href=\"https:\/\/reliefweb.int\/report\/occupied-palestinian-territory\/assessment-physical-damage-caused-buildings-war-gaza-october-2023-april-2024-enar\"><strong> d\u00e9truits<\/strong><\/a>, parmi lesquels 405 \u00e9coles et universit\u00e9s, 700 h\u00f4pitaux et antennes de soins de sant\u00e9, 290 mosqu\u00e9es et trois \u00e9glises. Au vu de l&rsquo;estimation de l&rsquo;organisation de contr\u00f4le de l&rsquo;ONU, l&rsquo;OCHA, qui dit qu&rsquo;\u00e0 chaque heure, 12 b\u00e2timents sont d\u00e9truits \u00e0 Gaza, le chiffre calcul\u00e9 en tenant compte des mois de mai et de juin est de 377 280 b\u00e2timents.<\/p>\n<p>&nbsp;<\/p>\n<h3>Morts et blessures dues aux tirs directs<\/h3>\n<p>\u2022<strong>Le nombre de <a href=\"https:\/\/www.facebook.com\/MOHGaza1994\/\" target=\"_blank\" rel=\"noopener\">martyrs <\/a>enregistr\u00e9 ce mercredi \u00e9tait de 37 718.<\/strong> Il convient de remarquer que ce chiffre ne comprend que les martyrs qui ont \u00e9t\u00e9 identifi\u00e9s au moyen de leur nom et de leur num\u00e9ro d&rsquo;identification civile via le minist\u00e8re de la sant\u00e9 \u00e0 Gaza, qui est soumis \u00e0 un si\u00e8ge permanent. En raison des pannes des syst\u00e8mes d&rsquo;enregistrement imputables aux destructions s\u00e9v\u00e8res des infrastructures et aux pertes de personnel, ce chiffre constitue une sous-estimation flagrante, m\u00eame avec ses param\u00e8tres limit\u00e9s. En s&rsquo;appuyant sur les chiffres plus appropri\u00e9s d&rsquo;environ <a href=\"https:\/\/www.aljazeera.com\/news\/longform\/2023\/11\/1\/know-their-names-palestinians-killed-in-israeli-attacks-on-gaza\" target=\"_blank\" rel=\"noopener\"><strong>370 personnes tu\u00e9es quotidiennement<\/strong><\/a>, multipli\u00e9s par 264 (le nombre de jours \u00e9coul\u00e9s depuis le d\u00e9but du g\u00e9nocide), le nombre r\u00e9el est plut\u00f4t proche de 97 680 martyrs. (Selon l&rsquo;estimation de l&rsquo;OCHA, de 15 martyrs par heure, en 264 jours, c&rsquo;est-\u00e0-dire 6 336 heures, ce nombre serait d&rsquo;environ 95 040 martyrs.).<\/p>\n<p>\u2022L&rsquo;estimation corrig\u00e9e du nombre de martyrs est de 260 pour 100 sup\u00e9rieure au nombre stagnant signal\u00e9. Il est raisonnable d&rsquo;ajuster le nombre de bless\u00e9s (actuellement de 86 377) selon le m\u00eame pourcentage, ce qui porterait ce nombre \u00e0 224 580. (Selon l&rsquo;estimation de l&rsquo;OCHA, de 35 bless\u00e9s par heure, ce nombre serait de 221 760.)<\/p>\n<p>&nbsp;<\/p>\n<h3>La mort par manque de m\u00e9dicaments et en raison de conditions chroniques<\/h3>\n<p>\u2022Remarque importante : Le nombre ci-dessus ne reprend pas les milliers de martyrs non identifi\u00e9s, dont certains ont \u00e9t\u00e9 retrouv\u00e9s dans des fosses communes ; ni ceux qui sont arriv\u00e9s sans t\u00eate ou d\u00e9chiquet\u00e9s en fragments impossibles \u00e0 identifier ; ni ceux qui ont \u00e9t\u00e9 inhum\u00e9s par leurs proches sans passer par le syst\u00e8me des h\u00f4pitaux ; ni ceux qui sont morts de faim ; ni ceux qui sont morts en raison du manque d&rsquo;acc\u00e8s \u00e0 des m\u00e9dicaments d&rsquo;importance vitale ; ni ceux qui sont morts d&rsquo;infections ou de maladies contagieuses.<\/p>\n<p>\u2022En tenant compte de 1 100 <a href=\"https:\/\/www.aljazeera.com\/news\/longform\/2023\/11\/1\/know-their-names-palestinians-killed-in-israeli-attacks-on-gaza\" target=\"_blank\" rel=\"noopener\"><strong>patients devant \u00eatre dialys\u00e9s<\/strong><\/a>, de 2 000 <a href=\"https:\/\/www.aljazeera.com\/news\/2023\/11\/14\/out-of-medicines-care-gazas-cancer-patients-face-death-amid-israel-war\" target=\"_blank\" rel=\"noopener\"><strong>canc\u00e9reux<\/strong><\/a> et de 341 000 individus d\u00e9pendant de m\u00e9dicaments pour g\u00e9rer des <strong><a href=\"https:\/\/www.emro.who.int\/images\/stories\/palestine\/oPt_Emergency_Situation_Update_-_NOV24.pdf\" target=\"_blank\" rel=\"noopener\">maladies chroniques<\/a><\/strong> (45 000 maladies cardiovasculaires, 71 000 diab\u00e8tes, 225 000 hypertensions), la p\u00e9nurie extr\u00eame de m\u00e9dicaments vitaux n&rsquo;a cess\u00e9 \u2013 et cela ne s&rsquo;arr\u00eatera pas \u2013 de provoquer des d\u00e9c\u00e8s dus au fait qu&rsquo;Isra\u00ebl emp\u00eache le passage des fournitures en tous genres. Si une estimation tr\u00e8s prudente de 5 pour 100 de ces patients doivent mourir pour cette raison (et s&rsquo;ils ne sont pas d\u00e9j\u00e0 morts), cela nous fait encore 17 050 personnes de plus.<\/p>\n<p>\u2022Cependant, un taux de mortalit\u00e9 plus exact (toutes causes confondues), pour un diab\u00e8te mal trait\u00e9, est de <strong><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6122181\/\" target=\"_blank\" rel=\"noopener\">13,6 pour 100<\/a> <\/strong>(portant la mortalit\u00e9 \u00e0 9 869 personnes) ; de<a href=\"https:\/\/academic.oup.com\/ajh\/article\/23\/1\/38\/149650?login=false\" target=\"_blank\" rel=\"noopener\"><strong> 37 pour 100<\/strong> <\/a>pour une hypertension non contr\u00f4l\u00e9e (se traduisant par 83 250 personnes) ; les dialyses non effectu\u00e9es et les patients du cancer auront un<a href=\"https:\/\/jamanetwork.com\/journals\/jamainternalmedicine\/fullarticle\/2730766\" target=\"_blank\" rel=\"noopener\"><strong> taux de mortalit\u00e9 tr\u00e8s \u00e9lev\u00e9.<\/strong><\/a> Une estimation prudente pour ce groupe est de 30 pour 100, soit 930 patients.<\/p>\n<p>\u2022Ensemble, cela nous fait 94 049 personnes (je ne prends pas les maladies cardiovasculaires uniquement, puisque les patients tendent \u00e0 pr\u00e9senter des comorbidit\u00e9s et qu&rsquo;il y aurait de ce fait un chevauchement dans les chiffres).<\/p>\n<p>&nbsp;<\/p>\n<h3>Les personnes mortes ou en train de mourir de faim<\/h3>\n<p>\u2022Selon un <a href=\"https:\/\/www.ipcinfo.org\/ipc-country-analysis\/details-map\/en\/c\/1157065\/\" target=\"_blank\" rel=\"noopener\"><strong>rapport<\/strong><\/a> de la Classification de la s\u00e9curit\u00e9 alimentaire int\u00e9gr\u00e9e appuy\u00e9e par l&rsquo;ONU (IPC), quelque 495 000 Palestiniens de Gaza sont confront\u00e9s \u00e0 une faim <em>\u00ab catastrophique \u00bb<\/em>, ce qui signifie qu&rsquo;ils souffrent d&rsquo;un manque extr\u00eame de nourriture d\u00e9bouchant sur une malnutrition aigu\u00eb parmi les jeunes enfants, un risque imminent de faim permanente et donc de mort. Si nous y allons d&rsquo;une estimation prudente de 5 pour 100 de d\u00e9c\u00e8s de faim dans cette population, nous en arrivons \u00e0 24 750 personnes mortes ou en train de mourir de faim.<\/p>\n<p>\u2022La mortalit\u00e9 bas\u00e9e sur des donn\u00e9es pour la malnutrition aigu\u00eb est approximativement de 20 pour 100. Cependant, la classification actuelle n&rsquo;a pas encore atteint des niveaux de famine totale, ce qui rend raisonnable l&rsquo;estimation actuelle.<\/p>\n<p>&nbsp;<\/p>\n<h3>Les personnes port\u00e9es manquantes, pr\u00e9sum\u00e9es mortes ou kidnapp\u00e9es<\/h3>\n<p>\u2022Environ <a href=\"https:\/\/truthout.org\/articles\/21000-children-are-missing-in-gaza-on-top-of-over-15000-killed-by-israel\/\" target=\"_blank\" rel=\"noopener\">21 000 enfants<\/a> ont \u00e9t\u00e9 port\u00e9s disparus et n&rsquo;entrent pas dans les comptes. Certains sont rest\u00e9s coinc\u00e9s sous les d\u00e9combres, certains ont \u00e9t\u00e9 kidnapp\u00e9s par les soldats isra\u00e9liens, alors que d&rsquo;autres se sont tout simplement \u00e9gar\u00e9s dans le chaos. \u00c9tant donn\u00e9 la proportion relativement \u00e9gale entre adultes et enfants \u00e0 Gaza, on peut pr\u00e9sumer avec une certaine certitude que le nombre des adultes non repris est du m\u00eame ordre, ce qui multiplie par deux ce nombre de personnes manquantes et le porte ainsi \u00e0 42 000.<\/p>\n<p>&nbsp;<\/p>\n<h3>La mort par maladie<\/h3>\n<p>\u2022En raison de la destruction des infrastructures de l&rsquo;eau et de son assainissement, associ\u00e9e aux restrictions sur l&rsquo;entr\u00e9e de l&rsquo;aide \u00e0 Gaza, l&rsquo;offensive isra\u00e9lienne a d\u00e9bouch\u00e9 sur une propagation de maladies transmissibles et caus\u00e9es par l&rsquo;eau, comme la jaunisse aigu\u00eb (due principalement \u00e0 l&rsquo;h\u00e9patite A), la diarrh\u00e9e aigu\u00eb (accompagn\u00e9e de sang dans les selles), la gale et les poux, les d\u00e9mangeaisons cutan\u00e9es, la variole et les infections respiratoires aigu\u00ebs, qui atteignaient <a href=\"https:\/\/reliefweb.int\/report\/occupied-palestinian-territory\/opt-emergency-situation-update-33-7-oct-2023-6-jun-2024-1600\" target=\"_blank\" rel=\"noopener\"><strong>un total de 1 440 805 cas<\/strong><\/a> \u00e0 la date du 10 juin. Si un seul pour 100 de ces patients succombent \u00e0 ces conditions graves, cela nous donnera quelque chose comme 14 408 individus tu\u00e9s indirectement par le si\u00e8ge et les bombardements isra\u00e9liens de Gaza.<\/p>\n<p>\u2022La mortalit\u00e9 r\u00e9sultant de la jaunisse aigu\u00eb ou h\u00e9patite A est faible (2,5 pour 100 chez les adultes et moins de 1 pour 100 chez les enfants) ; donc une estimation de mortalit\u00e9 de 1 pour 100 convient pour cette cat\u00e9gorie, soit 817 personnes) ; la mortalit\u00e9 r\u00e9sultant de la diarrh\u00e9e va <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/1421937\/\" target=\"_blank\" rel=\"noopener\"><strong>de 4,27 \u00e0 12 pour 100<\/strong><\/a> (de 20 722 \u00e0 58 238 personnes) ; la mortalit\u00e9 due \u00e0 la variole est <strong><a href=\"https:\/\/www.who.int\/teams\/health-product-policy-and-standards\/standards-and-specifications\/vaccine-standardization\/smallpox#:~:text=Two%20forms%20of%20the%20disease,most%20prominent%20on%20the%20face.\" target=\"_blank\" rel=\"noopener\">de 1 \u00e0 3 pour 100<\/a><\/strong>, en fonction de la pression (de 854 \u00e0 2 561 personnes) ; le taux de mortalit\u00e9 due \u00e0 des troubles respiratoires aigus va <strong><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK436002\/#:~:text=%5B6%5D%5B7%5D%20The,%2C%20and%20severe%20disease%2C%20respectively.\" target=\"_blank\" rel=\"noopener\">de 27 \u00e0 45 pour 100<\/a><\/strong>, selon la s\u00e9v\u00e9rit\u00e9 (ou entre 233 592 et 389 320 personnes). Tout mis ensemble et ajust\u00e9 aux donn\u00e9es scientifiques, les chiffres pour cette cat\u00e9gorie de martyrs vont de 255 985 \u00e0 450 936 personnes.<\/p>\n<p>&nbsp;<\/p>\n<h3>R\u00e9sum\u00e9s des estimations<\/h3>\n<p>En s&rsquo;appuyant sur ces estimations, tant prudentes que d\u00e9duites des donn\u00e9es, les chiffres r\u00e9els sont de l&rsquo;ordre de grandeur suivant :<\/p>\n<blockquote><p><strong>\u2022377 280 b\u00e2timents d\u00e9truits compl\u00e8tement ou en partie<\/strong><\/p>\n<p><strong>\u2022Entre 95 040 et 97 680 martyrs<\/strong><\/p>\n<p><strong>\u2022221 760 bless\u00e9s<\/strong><\/p>\n<p><strong>\u202224 750 personnes mortes ou en train de mourir de faim<\/strong><\/p>\n<p><strong>\u202242 000 personnes port\u00e9es manquantes (pr\u00e9sum\u00e9es mortes, kidnapp\u00e9es par les forces d&rsquo;occupation isra\u00e9liennes, voire peut-\u00eatre victimes de l&rsquo;un ou l&rsquo;autre trafic).<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Les chiffres suivants repr\u00e9sentent une estimation prudente ou la fourchette inf\u00e9rieure de population bas\u00e9e sur les donn\u00e9es :<\/p>\n<blockquote><p>\u2022<strong>Entre 17 050 et 94 049 personnes atteintes de maladies chroniques et mortes par manque de m\u00e9dicaments<\/strong><\/p>\n<p><strong>\u2022Entre 14 408 et 255 985 personnes mortes d&rsquo;\u00e9pid\u00e9mies r\u00e9sultant de l&rsquo;offensive isra\u00e9lienne<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>Cela signifie que <strong>le nombre r\u00e9el de morts est plus proche d&rsquo;entre 194 768 et 511 824 personnes<\/strong>, avec <strong>221 760 bless\u00e9s.<\/strong> Et ce n&rsquo;est qu&rsquo;un d\u00e9but.<\/p>\n<p>Ces chiffres ne comprennent pas les milliers de personnes qui ont \u00e9t\u00e9 kidnapp\u00e9es et sont actuellement tortur\u00e9es dans les goulags isra\u00e9liens :<a href=\"https:\/\/www.aa.com.tr\/en\/middle-east\/36-prisoners-tortured-to-death-in-israeli-jails-since-oct-7-gaza-media-office\/3254486\" target=\"_blank\" rel=\"noopener\"><strong> trois douzaines d&rsquo;entre elles<\/strong> <\/a>au moins ont \u00e9t\u00e9 tortur\u00e9es \u00e0 mort ou sont mortes dans des conditions extr\u00eamement insupportables.<\/p>\n<p>&nbsp;<\/p>\n<h3>Certaines vies comptent plus que d&rsquo;autres<\/h3>\n<p>Les estimations ici sont raisonnables mais des \u00e9tudes sur le terrain doivent \u00eatre r\u00e9alis\u00e9es imm\u00e9diatement. Les institutions internationales doivent \u00e9valuer d&rsquo;urgence la mortalit\u00e9 r\u00e9elle, toutes causes confondues, r\u00e9sultant directement et indirectement de l&rsquo;offensive isra\u00e9lienne contre Gaza.<\/p>\n<p>Jusqu&rsquo;\u00e0 pr\u00e9sent, des 240 captifs isra\u00e9liens \u00e0 Gaza, on suppose qu<a href=\"https:\/\/www.thedailybeast.com\/hamas-claims-50-hostages-killed-by-israeli-airstrikes-in-gaza\" target=\"_blank\" rel=\"noopener\">&lsquo;<strong>Isra\u00ebl en a tu\u00e9 lui-m\u00eame 50<\/strong><\/a>, soit directement (en les abattant), soit indirectement (en bombardant les b\u00e2timents dans lesquels ils se trouvaient) et a assur\u00e9 la lib\u00e9ration de 112 d&rsquo;entre eux : 105 via des <a href=\"https:\/\/www.aljazeera.com\/news\/2024\/2\/14\/how-many-israeli-captives-have-been-released-or-rescued\" target=\"_blank\" rel=\"noopener\"><strong>accords n\u00e9goci\u00e9s avec le Hamas<\/strong><\/a>, et<strong> <a href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/06\/27\/bombarder-et-affamer-gaza-ne-pourra-inverser-lechec-strategique-disrael\/\">sept<\/a><\/strong> au cours de missions de <em>\u00ab sauvetage \u00bb.<\/em><\/p>\n<p>La mission de <em>\u00ab sauvetage \u00bb<\/em> direct la plus r\u00e9cente s&rsquo;est traduite par la lib\u00e9ration de quatre captifs dans le camp de r\u00e9fugi\u00e9s de Nuseirat, dans le centre de la bande de Gaza. Un total de<strong> 274 Palestiniens<\/strong> et <a href=\"https:\/\/www.aljazeera.com\/news\/2024\/6\/11\/nuseirat-anatomy-of-israels-massacre-in-gaza\" target=\"_blank\" rel=\"noopener\"><strong>plusieurs captifs isra\u00e9liens<\/strong><\/a> ont \u00e9t\u00e9 tu\u00e9s au cours de la m\u00eame op\u00e9ration.<\/p>\n<p>Au moins un repr\u00e9sentant am\u00e9ricain estime qu&rsquo;il<strong><a href=\"https:\/\/www.facebook.com\/watch\/?v=1184459435898003\" target=\"_blank\" rel=\"noopener\"> vaut la peine<\/a><\/strong> de sacrifier des centaines de Palestiniens pour quatre Isra\u00e9liens. Il semble que seules certaines vies comptent.<\/p>\n<p>Je laisse les lecteurs calculer eux-m\u00eames quel est le niveau de mort et de destruction inflig\u00e9s \u00e0 Gaza par captif ou par combattant du Hamas.<\/p>\n<p>Il ne peut y avoir qu&rsquo;une seule conclusion, entre les deux propos\u00e9es ici. Soit l&rsquo;arm\u00e9e isra\u00e9lienne est la force la plus incomp\u00e9tente \u00e0 avoir jamais op\u00e9r\u00e9 sur cette plan\u00e8te \u2013 et elle n&rsquo;est dot\u00e9e d&rsquo;aucune capacit\u00e9 fiable de collecte de renseignements \u2013 soit Isra\u00ebl est une nation sadique anim\u00e9e d&rsquo;une intention de g\u00e9nocide contre une population autochtone, et son projet ressemble donc tr\u00e8s fortement \u00e0 tous les projets coloniaux de peuplement qui ont \u00e9maill\u00e9 l&rsquo;histoire.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">*****<\/p>\n<p>Publi\u00e9 le 27 juin 2024 sur<a href=\"https:\/\/electronicintifada.net\/content\/math-proves-israels-stated-goals-are-epic-lie\/47371\" target=\"_blank\" rel=\"noopener\"><strong> The Electronic Intifada<\/strong><\/a><br \/>\nTraduction : Jean-Marie Fl\u00e9mal, <a href=\"https:\/\/charleroi-pourlapalestine.be\/\"><strong>Charleroi pour la Palestine<\/strong><\/a><\/p>\n<p style=\"text-align: center;\">*****<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16514 size-thumbnail alignleft\" src=\"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/08\/susan-abulhawa-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\">Susan Abulhawa<\/strong> est n\u00e9e en 1967 en <strong>Palestine<\/strong>, de parents r\u00e9fugi\u00e9s de la guerre des Six-Jours. \u00c9lev\u00e9e en partie au <strong>Kowe\u00eft<\/strong>, en <strong>Jordanie<\/strong> et dans la partie occup\u00e9e de <strong>J\u00e9rusalem-Est<\/strong>, elle vit maintenant aux <strong>\u00c9tats-Unis<\/strong>.<\/p>\n<p><strong>Susan Abulhawa<\/strong> est l\u2019auteur de <em><strong>\u00ab Les Matins de J\u00e9nine \u00bb<\/strong><\/em> (\u00e9dit\u00e9 en fran\u00e7ais chez Buchet-Chastel en 2008), qui a remport\u00e9 le <em>Best Book Award 2007<\/em> dans la cat\u00e9gorie Fiction historique.<\/p>\n<p>Elle est commentatrice politique, activiste pour les droits humains et fondatrice d\u2019une organisation internationale pour la d\u00e9fense des enfants.<\/p>\n<p>Son premier recueil de po\u00e9sie <strong><em>\u00ab My voice sought the wind \u00bb<\/em><\/strong> est publi\u00e9 en 2013 chez Just World Books. Sa deuxi\u00e8me publication en fran\u00e7ais,<strong> \u00ab&nbsp;<em>Le Bleu entre le ciel et la mer&nbsp;\u00bb<\/em> <\/strong>(\u00ab The Blue between Sky and Water \u00bb), est \u00e9dit\u00e9 chez Deno\u00ebl, en 2016. Son dernier roman s\u2019appelle <em><strong>Against the Loveless World. Bloomsbury <\/strong><\/em>et est \u00e9dit\u00e9 chez Bloomsburry, Londres, en 2020<em><strong><br \/>\n<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsqu&rsquo;on se trouve \u00e0 Gaza et qu&rsquo;on voit les destructions de tout pr\u00e8s, la conclusion la plus \u00e9vidente est que les buts affirm\u00e9s d&rsquo;Isra\u00ebl ne sont qu&rsquo;un mensonge grandiloquent.<\/p>\n","protected":false},"author":1,"featured_media":73649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6,344],"tags":[242],"class_list":["post-73646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaza","category-genocide","tag-susan-abulhawa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gaza : les buts affirm\u00e9s d&#039;Isra\u00ebl ne sont qu&#039;un mensonge grandiloquent<\/title>\n<meta name=\"description\" content=\"Susan Abulhawa analyse les chiffres de la mort et des destructions \u00e0 Gaza, de la famine et des bless\u00e9s, des disparus et des martyrs\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/\"},\"author\":{\"name\":\"admin1873\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\"},\"headline\":\"Gaza : les buts affirm\u00e9s d&rsquo;Isra\u00ebl ne sont qu&rsquo;un mensonge grandiloquent\",\"datePublished\":\"2024-07-01T14:07:53+00:00\",\"dateModified\":\"2024-07-01T14:08:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/\"},\"wordCount\":1901,\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Genocide-a-Gaza.jpg\",\"keywords\":[\"Susan Abulhawa\"],\"articleSection\":[\"Gaza\",\"G\u00e9nocide\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/\",\"name\":\"Gaza : les buts affirm\u00e9s d'Isra\u00ebl ne sont qu'un mensonge grandiloquent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Genocide-a-Gaza.jpg\",\"datePublished\":\"2024-07-01T14:07:53+00:00\",\"dateModified\":\"2024-07-01T14:08:08+00:00\",\"description\":\"Susan Abulhawa analyse les chiffres de la mort et des destructions \u00e0 Gaza, de la famine et des bless\u00e9s, des disparus et des martyrs\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Genocide-a-Gaza.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Genocide-a-Gaza.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/2024\\\/07\\\/01\\\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaza : les buts affirm\u00e9s d&#8217;Isra\u00ebl ne sont qu&#8217;un mensonge grandiloquent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#website\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"name\":\"Charleroi Pour la Palestine\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#organization\",\"name\":\"Plate-forme Charleroi-Palestine\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"contentUrl\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo-Copy.jpg\",\"width\":180,\"height\":180,\"caption\":\"Plate-forme Charleroi-Palestine\"},\"image\":{\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlateformeCharleroiPalestine\\\/\",\"https:\\\/\\\/x.com\\\/LaCharleroi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/#\\\/schema\\\/person\\\/c19ff515112f1299d8c12671d8fe3faa\",\"name\":\"admin1873\",\"url\":\"https:\\\/\\\/charleroi-pourlapalestine.be\\\/index.php\\\/author\\\/admin1873\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaza : les buts affirm\u00e9s d'Isra\u00ebl ne sont qu'un mensonge grandiloquent","description":"Susan Abulhawa analyse les chiffres de la mort et des destructions \u00e0 Gaza, de la famine et des bless\u00e9s, des disparus et des martyrs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#article","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/"},"author":{"name":"admin1873","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa"},"headline":"Gaza : les buts affirm\u00e9s d&rsquo;Isra\u00ebl ne sont qu&rsquo;un mensonge grandiloquent","datePublished":"2024-07-01T14:07:53+00:00","dateModified":"2024-07-01T14:08:08+00:00","mainEntityOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/"},"wordCount":1901,"publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg","keywords":["Susan Abulhawa"],"articleSection":["Gaza","G\u00e9nocide"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/","name":"Gaza : les buts affirm\u00e9s d'Isra\u00ebl ne sont qu'un mensonge grandiloquent","isPartOf":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#primaryimage"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#primaryimage"},"thumbnailUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg","datePublished":"2024-07-01T14:07:53+00:00","dateModified":"2024-07-01T14:08:08+00:00","description":"Susan Abulhawa analyse les chiffres de la mort et des destructions \u00e0 Gaza, de la famine et des bless\u00e9s, des disparus et des martyrs","breadcrumb":{"@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#primaryimage","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2024\/07\/Genocide-a-Gaza.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/charleroi-pourlapalestine.be\/index.php\/2024\/07\/01\/gaza-les-buts-affirmes-disrael-ne-sont-quun-mensonge-grandiloquent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charleroi-pourlapalestine.be\/"},{"@type":"ListItem","position":2,"name":"Gaza : les buts affirm\u00e9s d&#8217;Isra\u00ebl ne sont qu&#8217;un mensonge grandiloquent"}]},{"@type":"WebSite","@id":"https:\/\/charleroi-pourlapalestine.be\/#website","url":"https:\/\/charleroi-pourlapalestine.be\/","name":"Charleroi Pour la Palestine","description":"","publisher":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charleroi-pourlapalestine.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/charleroi-pourlapalestine.be\/#organization","name":"Plate-forme Charleroi-Palestine","url":"https:\/\/charleroi-pourlapalestine.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/","url":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","contentUrl":"https:\/\/charleroi-pourlapalestine.be\/wp-content\/uploads\/2020\/01\/logo-Copy.jpg","width":180,"height":180,"caption":"Plate-forme Charleroi-Palestine"},"image":{"@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlateformeCharleroiPalestine\/","https:\/\/x.com\/LaCharleroi"]},{"@type":"Person","@id":"https:\/\/charleroi-pourlapalestine.be\/#\/schema\/person\/c19ff515112f1299d8c12671d8fe3faa","name":"admin1873","url":"https:\/\/charleroi-pourlapalestine.be\/index.php\/author\/admin1873\/"}]}},"_links":{"self":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/73646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/comments?post=73646"}],"version-history":[{"count":0,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/posts\/73646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media\/73649"}],"wp:attachment":[{"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/media?parent=73646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/categories?post=73646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charleroi-pourlapalestine.be\/index.php\/wp-json\/wp\/v2\/tags?post=73646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}